{"id":158736,"date":"2024-03-26T10:26:54","date_gmt":"2024-03-26T14:26:54","guid":{"rendered":"https:\/\/innowise.com\/?page_id=158736"},"modified":"2026-04-17T09:31:39","modified_gmt":"2026-04-17T13:31:39","slug":"logistics","status":"publish","type":"page","link":"https:\/\/innowise.com\/sv\/industries\/logistics\/","title":{"rendered":"Tj\u00e4nster f\u00f6r utveckling av programvara f\u00f6r logistik"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"158736\" class=\"elementor elementor-158736\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a8068e container-header back-animations e-flex e-con-boxed e-con e-parent\" data-id=\"8a8068e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f00ae9c e-con-full e-flex e-con e-child\" data-id=\"f00ae9c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cac9ca elementor-widget__width-inherit word-break elementor-widget elementor-widget-heading\" data-id=\"2cac9ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Logistics software development services<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-939b729 elementor-widget-tablet__width-inherit elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"939b729\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tired of late deliveries and fragmented systems eating into your margins? Innowise\u2019s logistics software development services bring live tracking, AI-driven routing, and automated workflows into your supply chain, so you slash costs and hit every ETA.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58a075c elementor-align-center elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"58a075c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Start my solution<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ebf27bc e-flex e-con-boxed e-con e-parent\" data-id=\"ebf27bc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2d4c472 e-con-full e-flex e-con e-child\" data-id=\"2d4c472\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-281353d elementor-widget elementor-widget-text-editor\" data-id=\"281353d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>40+<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9925f33 elementor-widget elementor-widget-text-editor\" data-id=\"9925f33\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>logistics software development projects<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f9c391 e-con-full e-flex e-con e-child\" data-id=\"3f9c391\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf6a7d elementor-widget elementor-widget-text-editor\" data-id=\"4cf6a7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>60+<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bea0d79 elementor-widget elementor-widget-text-editor\" data-id=\"bea0d79\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>logistics developers<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-71ef8f0 e-con-full e-flex e-con e-child\" data-id=\"71ef8f0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10b871b elementor-widget elementor-widget-text-editor\" data-id=\"10b871b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span id=\"years-expirience\">19+<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f18f8d2 elementor-widget elementor-widget-text-editor\" data-id=\"f18f8d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>years delivering logistics software<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7a97e4 e-con-full e-flex e-con e-child\" data-id=\"c7a97e4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-968ee54 elementor-widget elementor-widget-text-editor\" data-id=\"968ee54\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>75%<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2708bee elementor-widget elementor-widget-text-editor\" data-id=\"2708bee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>mid to senior-level professionals<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f57ce9d e-flex e-con-boxed e-con e-parent\" data-id=\"f57ce9d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b84a7e elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"3b84a7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Business benefits of custom logistics software development<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d98df4 switcher-section elementor-widget elementor-widget-html\" data-id=\"6d98df4\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"domains-container-new\">\r\n  <ul class=\"domains__list-new\">\r\n    <li class=\"active\">Supply chain transparency<\/li>\r\n    <li>Data-driven decision-making<\/li>\r\n    <li>Reduced costs<\/li>\r\n    <li>Boosted operational efficiency<\/li>\r\n    <li>Business risk mitigation<\/li>\r\n    <li>Growth acceleration<\/li>\r\n  <\/ul>\r\n\r\n  <div class=\"domains__descriptions-new\">\r\n    <div class=\"swiper-wrapper\">\r\n      \r\n      <div class='swiper-slide swiper-slide-active'>\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Supply chain transparency<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">\r\n            Lose the blind spots with logistics software development. Live updates on shipments, stock, and supplier keep every link visible, flagging issues early so bottlenecks fade and delays never snowball into costs.\r\n          <\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Supply-chain-transparency.png\" alt=\"Supply Chain Transparency\">\r\n        <\/div>\r\n      <\/div>\r\n\r\n      <div class='swiper-slide'>\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Data-driven decision-making<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">\r\n            Turn raw order, transit, and inventory data into clear tactical insights. Hard numbers guide every move, tightening plans, lifting performance, and keeping you a step ahead of the competition.\r\n          <\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Data-driven-decision-making.png\" alt=\"Data Driven Decision Making\">\r\n        <\/div>\r\n      <\/div>\r\n\r\n      <div class='swiper-slide'>\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Reduced costs<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">\r\n            Cut unnecessary expenses by automating routine tasks, optimizing routes, and erasing manual errors. Fuel bills shrink, labor hours drop, and waste vanishes, so more savings hit your bottom line.\r\n          <\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Reduced-costs.png\" alt=\"Reduced Costs\">\r\n        <\/div>\r\n      <\/div>\r\n\r\n      <div class='swiper-slide'>\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Boosted operational efficiency<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">\r\n            Trim friction from every handoff, from order to doorstep. Automate picking instructions, sync warehouse-to-transport schedules, and let teams focus on high-impact work instead of firefighting.\r\n          <\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Boosted-operational-efficiency.png\" alt=\"Boosted Operational Efficiency\">\r\n        <\/div>\r\n      <\/div>\r\n\r\n      <div class='swiper-slide'>\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Business risk mitigation<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">\r\n            Catch problems before they hit your bottom line. Get instant alerts for late shipments, equipment glitches, and compliance issues. Predict maintenance needs and sail through any audit stress-free.\r\n          <\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Business-risk-mitigation.png\" alt=\"Business Risk Mitigation\">\r\n        <\/div>\r\n      <\/div>\r\n\r\n      <div class='swiper-slide'>\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Growth acceleration<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">\r\n            Scale your business by tearing down systems. Our flexible solutions let you add new routes, onboard partners, and expand into fresh markets fast. It grows with your ambitions, never holding you back.\r\n          <\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Growth-acceleration.png\" alt=\"Growth Acceleration\">\r\n        <\/div>\r\n      <\/div>\r\n\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\r\n\r\n<div class=\"mobile-domains-new\">\r\n  \r\n  <div class=\"mobile-domains-navitem-new active\" data-mobile-domain=\"domain-1\">\r\n    <span>Supply chain transparency<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">\r\n      Lose the blind spots with logistics software development. Live updates on shipments, stock, and supplier keep every link visible, flagging issues early so bottlenecks fade and delays never snowball into costs.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Supply-chain-transparency.png\" alt=\"Supply Chain Transparency\">\r\n    <\/p>\r\n  <\/div>\r\n  \r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-2\">\r\n    <span>Data-driven decision-making<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">\r\n      Turn raw order, transit, and inventory data into clear tactical insights. Hard numbers guide every move, tightening plans, lifting performance, and keeping you a step ahead of the competition.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Data-driven-decision-making.png\" alt=\"Data Driven Decision Making\">\r\n    <\/p>\r\n  <\/div>\r\n  \r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-3\">\r\n    <span>Reduced costs<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">\r\n      Cut unnecessary expenses by automating routine tasks, optimizing routes, and erasing manual errors. Fuel bills shrink, labor hours drop, and waste vanishes, so more savings hit your bottom line.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Reduced-costs.png\" alt=\"Reduced Costs\">\r\n    <\/p>\r\n  <\/div>\r\n  \r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-4\">\r\n    <span>Boosted operational efficiency<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">\r\n      Trim friction from every handoff, from order to doorstep. Automate picking instructions, sync warehouse-to-transport schedules, and let teams focus on high-impact work instead of firefighting.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Boosted-operational-efficiency.png\" alt=\"Boosted Operational Efficiency\">\r\n    <\/p>\r\n  <\/div>\r\n  \r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-5\">\r\n    <span>Business risk mitigation<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">\r\n      Catch problems before they hit your bottom line. Get instant alerts for late shipments, equipment glitches, and compliance issues. Predict maintenance needs and sail through any audit stress-free.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Business-risk-mitigation.png\" alt=\"Business Risk Mitigation\">\r\n    <\/p>\r\n  <\/div>\r\n  \r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-6\">\r\n    <span>Growth acceleration<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">\r\n      Scale your business by tearing down systems. Our flexible solutions let you add new routes, onboard partners, and expand into fresh markets fast. It grows with your ambitions, never holding you back.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Growth-acceleration.png\" alt=\"Growth Acceleration\">\r\n    <\/p>\r\n  <\/div>\r\n\r\n<\/div>\r\n\r\n\r\n\r\n<script>\r\n\r\ndocument.addEventListener('DOMContentLoaded', () => {\r\n    const mobileNavItems = document.querySelectorAll('.mobile-domains-navitem-new');\r\n\r\n    mobileNavItems.forEach(item => {\r\n        item.addEventListener('click', () => {\r\n            const isActive = item.classList.contains('active');\r\n\r\n            \/\/ Collapse all items\r\n            mobileNavItems.forEach(nav => {\r\n                nav.classList.remove('active');\r\n                const ul = nav.querySelector('.mobile-domain-list');\r\n                if (ul) ul.style.maxHeight = '0';\r\n            });\r\n\r\n            \/\/ Expand clicked item only if it was not active\r\n            if (!isActive) {\r\n                item.classList.add('active');\r\n                const ul = item.querySelector('.mobile-domain-list');\r\n                if (ul) ul.style.maxHeight = ul.scrollHeight + 'px';\r\n            }\r\n        });\r\n    });\r\n    \r\n    const firstNavItem = mobileNavItems.item(0);\r\n    \r\n    if (firstNavItem && !firstNavItem.classList.contains('active')) {\r\n        firstNavItem.click();\r\n    }\r\n});\r\n\r\n<\/script>\r\n\r\n\r\n<script>\r\n\r\ndocument.addEventListener('DOMContentLoaded', () => {\r\n    \r\n  const domainsSwiper = new Swiper('.domains__descriptions-new', {\r\n    slidesPerView: 1,\r\n   spaceBetween: 24, \r\n       effect:'fade',\r\n    allowTouchMove:false,   \r\n       \r\n  });  \r\n    \r\n\r\nconst domainsListItems = document.querySelectorAll(\r\n  '.domains__list-new li'\r\n);\r\n\r\nconst rightPart = document.querySelector(\r\n  '.domains__descriptions-new'\r\n);\r\n\r\nconst leftPart = document.querySelector(\r\n  '.domains__list-new'\r\n);\r\n\r\n\r\nconst rightPartHeight = rightPart.getBoundingClientRect().height\r\n\r\nif(rightPartHeight > leftPart.getBoundingClientRect().height){\r\n    leftPart.style.minHeight = `${rightPartHeight}px`;\r\n}\r\n\r\n\r\n\r\n\r\n\r\ndomainsListItems.forEach((domainsListItem, domainsListItemIndex, arr) => {\r\n    \r\n  domainsListItem.addEventListener('click', () => {\r\n    arr.forEach((item,i) => {\r\n      if (item === domainsListItem) {\r\n        item.classList.add('active');\r\n        domainsSwiper.slideTo(i);\r\n      } else {\r\n        item.classList.remove('active');\r\n      }\r\n    });\r\n    \r\n  });\r\n});\r\n\r\n\r\n\r\n\r\n\r\n});\r\n\r\n<\/script>\r\n\r\n\r\n\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7fd67b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7fd67b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-21f2df2\" data-id=\"21f2df2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c2e60d elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"9c2e60d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Featured logistics software development projects\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32b8d51 elementor-widget elementor-widget-shortcode\" data-id=\"32b8d51\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n        <div class=\"slider-overflow\">\n            <div class=\"swiper-related\">\n                <div class=\"swiper-wrapper\">\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/ship-tracking-software\/\" aria-label=\"block_141193\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2023\/11\/Maritime-navigation-system-Wartsila-Small-cover.png\" alt=\"Maritime navigation system.\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/ship-tracking-software\/\" aria-label=\"Maritime navigation system\" >Maritime navigation system<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/logistics\/\">Logistics<\/a><a href=\"\/sv\/cases\/azure\/\">Azure<\/a><a href=\"\/sv\/cases\/backend-utveckling\/\">Back-end development<\/a><a href=\"\/sv\/cases\/cloud\/\">Cloud<\/a><a href=\"\/sv\/cases\/integrering\/\">Integration<\/a><a href=\"\/sv\/cases\/net\/\">.NET<\/a><a href=\"\/sv\/cases\/react\/\">React<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/ship-tracking-software\/\" aria-label=\"Read more about Maritime navigation system\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/enterprise-resource-planning-and-management-solution\/\" aria-label=\"block_96124\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/12\/OneStop-tizer.jpg\" alt=\"Enterprise resources management system.\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/enterprise-resource-planning-and-management-solution\/\" aria-label=\"Enterprise resources management system\" >Enterprise resources management system<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/logistics\/\">Logistics<\/a><a href=\"\/sv\/cases\/cloud\/\">Cloud<\/a><a href=\"\/sv\/cases\/construction\/\">Construction<\/a><a href=\"\/sv\/cases\/enterprise\/\">Enterprise<\/a><a href=\"\/sv\/cases\/erp\/\">ERP<\/a><a href=\"\/sv\/cases\/java\/\">Java<\/a><a href=\"\/sv\/cases\/angular\/\">Angular<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/enterprise-resource-planning-and-management-solution\/\" aria-label=\"Read more about Enterprise resources management system\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/truck-fleet-management-system-for-transportation-company\/\" aria-label=\"block_83301\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/03\/Teaser-Truck-Fleet.png\" alt=\"Truck fleet management system for transportation company.\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/truck-fleet-management-system-for-transportation-company\/\" aria-label=\"Truck fleet management system for transportation company\" >Truck fleet management system for transportation company<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/logistics\/\">Logistics<\/a><a href=\"\/sv\/cases\/business-intelligence\/\">Business intelligence<\/a><a href=\"\/sv\/cases\/datahantering\/\">Data management (DMS)<\/a><a href=\"\/sv\/cases\/net\/\">.NET<\/a><a href=\"\/sv\/cases\/react\/\">React<\/a><a href=\"\/sv\/cases\/transportation\/\">Transportation<\/a><a href=\"\/sv\/cases\/typescript\/\">TypeScript<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/truck-fleet-management-system-for-transportation-company\/\" aria-label=\"Read more about Truck fleet management system for transportation company\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/iot-plant-watering-system\/\" aria-label=\"block_196663\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/05\/image-teaser-1.png\" alt=\"Intelligent IoT-based robot to navigate the office and water plants.\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/iot-plant-watering-system\/\" aria-label=\"Intelligent IoT-based robot to navigate the office and water plants\" >Intelligent IoT-based robot to navigate the office and water plants<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/aws\/\">AWS<\/a><a href=\"\/sv\/cases\/computer-vision\/\">Computer vision<\/a><a href=\"\/sv\/cases\/embedded\/\">Embedded<\/a><a href=\"\/sv\/cases\/iot\/\">IoT<\/a><a href=\"\/sv\/cases\/js\/\">JavaScript<\/a><a href=\"\/sv\/cases\/python\/\">Python<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/iot-plant-watering-system\/\" aria-label=\"Read more about Intelligent IoT-based robot to navigate the office and water plants\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/salesforce-implementation-process-transformation\/\" aria-label=\"block_195990\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/05\/image-teaser.png\" alt=\"Innowise&#8217;s Salesforce rollout and business process overhaul.\">\n                    <div class=\"cases-post__thumbnail_opencase_img\">\n                        <div>\n                            <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/04\/Log\u043es-desktop-1.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                \n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/salesforce-implementation-process-transformation\/\" aria-label=\"Innowise's Salesforce rollout and business process overhaul\" >Innowise's Salesforce rollout and business process overhaul<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/business-process-automation-bpa\/\">Business process automation (BPA)<\/a><a href=\"\/sv\/cases\/cloud\/\">Cloud<\/a><a href=\"\/sv\/cases\/it\/\">Information technology<\/a><a href=\"\/sv\/cases\/salesforce\/\">Salesforce<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/salesforce-implementation-process-transformation\/\" aria-label=\"Read more about Innowise's Salesforce rollout and business process overhaul\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/ai-assisted-contract-parsing-platform\/\" aria-label=\"block_195705\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/04\/image.jpg\" alt=\"AI-assisted contract transformation platform (DORA \/ NIS2 ready).\">\n                    <div class=\"cases-post__thumbnail_opencase_img\">\n                        <div>\n                            <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/04\/Log\u043es-desktop-1-1.png\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                \n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/ai-assisted-contract-parsing-platform\/\" aria-label=\"AI-assisted contract transformation platform (DORA \/ NIS2 ready)\" >AI-assisted contract transformation platform (DORA \/ NIS2 ready)<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/ai\/\">AI<\/a><a href=\"\/sv\/cases\/business-process-automation-bpa\/\">Business process automation (BPA)<\/a><a href=\"\/sv\/cases\/java\/\">Java<\/a><a href=\"\/sv\/cases\/legal\/\">Legal<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/ai-assisted-contract-parsing-platform\/\" aria-label=\"Read more about AI-assisted contract transformation platform (DORA \/ NIS2 ready)\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/gestical-platform-modernization\/\" aria-label=\"block_194759\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/03\/smart-meter-integration.png\" alt=\"Modernization of Gestical\u2019s operational platform.\">\n                    <div class=\"cases-post__thumbnail_opencase_img\">\n                        <div>\n                            <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/03\/gestical.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                \n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/gestical-platform-modernization\/\" aria-label=\"Modernization of Gestical\u2019s operational platform\" >Modernization of Gestical\u2019s operational platform<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/energy\/\">Energy<\/a><a href=\"\/sv\/cases\/staff-augmentation\/\">Staff augmentation<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/gestical-platform-modernization\/\" aria-label=\"Read more about Modernization of Gestical\u2019s operational platform\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/ai-ergonomics-software-scaling\/\" aria-label=\"block_195080\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/03\/image.png\" alt=\"Scaling AI ergonomics assessment software.\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/ai-ergonomics-software-scaling\/\" aria-label=\"Scaling AI ergonomics assessment software\" >Scaling AI ergonomics assessment software<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/angular\/\">Angular<\/a><a href=\"\/sv\/cases\/backend-utveckling\/\">Back-end development<\/a><a href=\"\/sv\/cases\/enterprise\/\">Enterprise<\/a><a href=\"\/sv\/cases\/frontend-utveckling\/\">Front-end development<\/a><a href=\"\/sv\/cases\/node-js\/\">Node.js<\/a><a href=\"\/sv\/cases\/qa\/\">QA<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/ai-ergonomics-software-scaling\/\" aria-label=\"Read more about Scaling AI ergonomics assessment software\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n                <\/div>\n                \n                <div class=\"swiper-related__navigation\">\n                    <button class=\"swiper-related__navigation-btn\">\n                        <svg width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <g>\n                                <path d=\"M12 4L4 12L12 20\" stroke=\"#2E2E2E\" stroke-width=\"2\"\/>\n                                <path d=\"M21 12.0002L4 12.0002\" stroke=\"#2E2E2E\" stroke-width=\"2\"\/>\n                            <\/g>\n                        <\/svg>\n                    <\/button>\n                \n                    <button class=\"swiper-related__navigation-btn\">\n                        <svg width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M13 4L21 12L13 20\" stroke=\"#2E2E2E\" stroke-width=\"2\"\/>\n                            <path d=\"M4 12.0002L21 12.0002\" stroke=\"#2E2E2E\" stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/button>\n                <\/div>\n            <\/div>\n        <\/div>\n\n        <div class=\"cases-swiper-pagination\"><\/div>\n        \n        <script src=\"\/wp-content\/themes\/hello-elementor\/assets\/js\/slb-case.js\"><\/script>  \n        <link rel=\"stylesheet\" href=\"\/wp-content\/themes\/hello-elementor\/assets\/css\/case-slider.css\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5bccc1 e-flex e-con-boxed e-con e-parent\" data-id=\"a5bccc1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2624b96 elementor-widget elementor-widget-html\" data-id=\"2624b96\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"display:none !important; margin-top: 0; padding: 0;\" class=\"m-technological-all\">\n        <span><a style=\"all: unset; cursor: pointer;\" href=\"https:\/\/innowise.com\/cases\/\">All case studies<\/a><\/span>\n    <\/div>\n   \n    \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7372d90 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7372d90\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1865e97\" data-id=\"1865e97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e8f40c elementor-widget elementor-widget-shortcode\" data-id=\"3e8f40c\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">[clients_logos]<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-ce2553f radGreedWrapper link-underline e-flex e-con-boxed e-con e-parent\" data-id=\"ce2553f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0519b54 elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"0519b54\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our scope of logistics &amp; transportation software development services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba04cae e-grid e-con-full e-con e-child\" data-id=\"ba04cae\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e3a940b e-flex e-con-boxed e-con e-child\" data-id=\"e3a940b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13bdca9 elementor-widget elementor-widget-text-editor\" data-id=\"13bdca9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Warehouse management<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e21cf1 elementor-widget elementor-widget-text-editor\" data-id=\"7e21cf1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Inventory moves at full tilt. WMS tracks stock automatically, guides picking routes, and keeps your warehouses synced, so you can move goods faster and cut down on errors.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-84824dd e-flex e-con-boxed e-con e-child\" data-id=\"84824dd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3d45a1 elementor-widget elementor-widget-text-editor\" data-id=\"f3d45a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Demand forecasting<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-883169f elementor-widget elementor-widget-text-editor\" data-id=\"883169f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Data drives your next move. Our team builds forecasting tools that blend sales and market trends to predict demand accurately. Plan confidently, avoid stockouts, and cut waste.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dc04c2 e-flex e-con-boxed e-con e-child\" data-id=\"6dc04c2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48e5955 elementor-widget elementor-widget-text-editor\" data-id=\"48e5955\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Order management<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61e0448 elementor-widget elementor-widget-text-editor\" data-id=\"61e0448\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centralize orders from every channel, route to the best warehouse, merge shipments, and process returns fast. Fulfillment speeds up, errors drop, and customers stick around.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6825d28 e-flex e-con-boxed e-con e-child\" data-id=\"6825d28\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6325ccd elementor-widget elementor-widget-text-editor\" data-id=\"6325ccd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Last-mile delivery solutions<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa7186 elementor-widget elementor-widget-text-editor\" data-id=\"3fa7186\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We craft delivery platforms that pick the fastest routes, stream live ETAs, and capture proof of delivery with a tap. Transit times shrink, schedules stay tight, and customer satisfaction soars.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-203b78f e-flex e-con-boxed e-con e-child\" data-id=\"203b78f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d36146 elementor-widget elementor-widget-text-editor\" data-id=\"2d36146\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Workflow management<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2059853 elementor-widget elementor-widget-text-editor\" data-id=\"2059853\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Automate routine tasks so you can track every move and spot hold-ups fast. Keep teams moving with total visibility into what\u2019s happening, where, and when.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6c5152 e-con-full e-flex e-con e-child\" data-id=\"b6c5152\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68b9b7f elementor-widget elementor-widget-text-editor\" data-id=\"68b9b7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Logistics reporting &amp; BI<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b8f108 elementor-widget elementor-widget-text-editor\" data-id=\"9b8f108\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>You shouldn\u2019t have to dig for answers. Our team turns your logistics data into clear dashboards so you can track performance, spot trends, and make faster decisions.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-225d7fa e-con-full e-flex e-con e-child\" data-id=\"225d7fa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b950120 elementor-widget elementor-widget-text-editor\" data-id=\"b950120\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Transport management<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cd0a02 elementor-widget elementor-widget-text-editor\" data-id=\"8cd0a02\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>From first dispatch to final drop-off, TMS keeps your shipments moving and schedules tight. Track every load, react to changes instantly, and keep your operation running lean.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cfe2e5 e-con-full e-flex e-con e-child\" data-id=\"1cfe2e5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd1d5e5 elementor-widget elementor-widget-text-editor\" data-id=\"bd1d5e5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Fleet management<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2ec202 elementor-widget elementor-widget-text-editor\" data-id=\"b2ec202\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our experts build fleet tools that track vehicle health, schedule maintenance, optimize routes, and monitor drivers in real time. Run leaner, cut downtime, and slash operating costs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5e50f7 e-con-full e-flex e-con e-child\" data-id=\"b5e50f7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e09f85c elementor-widget elementor-widget-text-editor\" data-id=\"e09f85c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Logistics automation<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ca800f elementor-widget elementor-widget-text-editor\" data-id=\"2ca800f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Leverage advanced software alongside robotics, smart conveyors, and autonomous vehicles to speed up storage, retrieval, palletization, and sorting. You\u2019ll cut labor and boost throughput.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00ea041 e-grid e-con-full e-con e-child\" data-id=\"00ea041\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9f5a417 e-con-full e-flex e-con e-child\" data-id=\"9f5a417\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-138df31 imgMobile240 elementor-widget elementor-widget-image\" data-id=\"138df31\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"668\" height=\"500\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/11\/Frame-1597885559-2.png\" class=\"attachment-full size-full wp-image-188938\" alt=\"image for CTA\" srcset=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/11\/Frame-1597885559-2.png 668w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/11\/Frame-1597885559-2-300x225.png 300w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/11\/Frame-1597885559-2-16x12.png 16w\" sizes=\"(max-width: 668px) 100vw, 668px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c6e852 e-con-full e-flex e-con e-child\" data-id=\"1c6e852\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-18309a2 e-con-full e-flex e-con e-child\" data-id=\"18309a2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8c41d5 elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"a8c41d5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Poor routes drain your budget? <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0de7ea elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial tabletmax510 elementor-widget elementor-widget-text-editor\" data-id=\"e0de7ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Let AI-powered routing software slash miles and fuel spend.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36bf1af elementor-align-center contact320 elementor-widget elementor-widget-button\" data-id=\"36bf1af\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Optimize routes<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-644e018 e-flex e-con-boxed e-con e-parent\" data-id=\"644e018\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e37ce82 elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"e37ce82\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Logistics software solutions we offer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ebdee1 elementor-widget elementor-widget-html\" data-id=\"8ebdee1\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"python-container\">\n    \n    <a class=\"python-item\" href=\"https:\/\/innowise.com\/services\/erp\/\">\n    <div>\n        <span class=\"python-item-title\">ERP<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/336.png\" \/ alt=\"\">\n    <\/div>\n\n    <\/a>\n    <a class=\"python-item\" href=\"https:\/\/innowise.com\/services\/supply-chain-management-software\/\">\n        <div class=\"python-item\">\n        <span class=\"python-item-title\">SCM<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/108.svg\" \/ alt=\"\">\n    <\/div>\n    <\/a>\n    \n    <div class=\"python-item\">\n        <span class=\"python-item-title\">Fleet management<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/09\/153.svg\" \/ alt=\"\">\n    <\/div>\n    \n    <div class=\"python-item\">\n        <span class=\"python-item-title\">Logistics scheduling\n<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/05\/350-1.svg\" \/ alt=\"\">\n    <\/div>\n    \n    <a class=\"python-item\" href=\"https:\/\/innowise.com\/industries\/transportation\/\">\n        <div class=\"python-item\">\n            <span class=\"python-item-title\">Transport management<\/span>\n            <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/01\/238.svg\" \/ alt=\"\">\n        <\/div>\n    <\/a>\n    \n    <a class=\"python-item\" href=\"https:\/\/innowise.com\/services\/crm\/development\/\">\n        <div class=\"python-item\">\n            <span class=\"python-item-title\">CRM systems<\/span>\n            <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/110.svg\" \/ alt=\"\">\n        <\/div>\n    <\/a>\n  \n<\/div>\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c55059e e-flex e-con-boxed e-con e-parent\" data-id=\"c55059e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e51c273 e-con-full e-flex e-con e-child\" data-id=\"e51c273\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-565834e elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"565834e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>When you move goods at scale, small mistakes cost real money. We dive into your workflows, zero in on bottlenecks, and build software that fixes them for good. You\u2019ll see the impact every day in smoother operations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48b821f e-con-full e-flex e-con e-child\" data-id=\"48b821f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd03b18 elementor-widget elementor-widget-heading\" data-id=\"dd03b18\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/innowise.com\/authors\/ivan-shatukha\/\">Ivan Shatukha<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1d24a6 elementor-widget elementor-widget-heading\" data-id=\"a1d24a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Global Development Director<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7be11c0 e-con-full e-flex e-con e-child\" data-id=\"7be11c0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e9685b5 elementor-widget elementor-widget-image\" data-id=\"e9685b5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"450\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Ivan-Shatuho.png\" class=\"attachment-full size-full wp-image-184119\" alt=\"\" srcset=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Ivan-Shatuho.png 500w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Ivan-Shatuho-300x270.png 300w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Ivan-Shatuho-13x12.png 13w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d88b66d radGreedWrapper link-underline e-flex e-con-boxed e-con e-parent\" data-id=\"d88b66d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c55e4a8 elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"c55e4a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Advanced technology expertise for logistics software development<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04a6023 e-grid e-con-full e-con e-child\" data-id=\"04a6023\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8bea3e9 e-flex e-con-boxed e-con e-child\" data-id=\"8bea3e9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84ed821 elementor-widget elementor-widget-text-editor\" data-id=\"84ed821\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">IoT for logistics<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fdcace elementor-widget elementor-widget-text-editor\" data-id=\"7fdcace\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sensors on every truck, pallet, and shelf stream live location and condition data. You get restock alerts the moment inventory dips and maintenance warnings before equipment fails.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c22eb47 e-flex e-con-boxed e-con e-child\" data-id=\"c22eb47\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f23cf69 elementor-widget elementor-widget-text-editor\" data-id=\"f23cf69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Big data for logistics<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6e065c elementor-widget elementor-widget-text-editor\" data-id=\"d6e065c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Your data tells the story. We just connect the dots across orders, traffic, weather, and internal systems. Get rock-solid forecasts, better planning, and no more last-minute firefighting.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24de000 e-flex e-con-boxed e-con e-child\" data-id=\"24de000\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eaf0143 elementor-widget elementor-widget-text-editor\" data-id=\"eaf0143\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Cloud logistics solutions<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-714aff7 elementor-widget elementor-widget-text-editor\" data-id=\"714aff7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Host your data in the cloud for instant updates, smooth collaboration, and auto-scaling when demand spikes. Tear down silos, speed up decision-making, and keep every team in sync.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5aade7 e-flex e-con-boxed e-con e-child\" data-id=\"a5aade7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a27fb2e elementor-widget elementor-widget-text-editor\" data-id=\"a27fb2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">AI in logistics<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44034c8 elementor-widget elementor-widget-text-editor\" data-id=\"44034c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Supercharge your supply chain. Predict demand, pick optimal routes, and deploy autonomous tech. Costs drop, deliveries speed up, and last-mile headaches disappear.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07552fc e-flex e-con-boxed e-con e-child\" data-id=\"07552fc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-801fdd8 elementor-widget elementor-widget-text-editor\" data-id=\"801fdd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Blockchain<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0ec7f elementor-widget elementor-widget-text-editor\" data-id=\"7b0ec7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Blockchain powers total supply chain visibility. Each transaction and handoff locks into an unchangeable ledger. Track every step, catch errors early, and watch disputes vanish.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d5992c5 e-con-full e-flex e-con e-child\" data-id=\"d5992c5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4eb521 elementor-widget elementor-widget-text-editor\" data-id=\"a4eb521\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Machine learning<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf8abf9 elementor-widget elementor-widget-text-editor\" data-id=\"bf8abf9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Turn data into a predictive engine. We train models to tighten forecasts, surface delays before they hit, and zap bottlenecks. The longer they run, the smarter they get.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cbab593 e-flex e-con-boxed e-con e-parent\" data-id=\"cbab593\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5903c4f e-con-full e-flex e-con e-child\" data-id=\"5903c4f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c23bcea elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"c23bcea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Crush inventory mismatches with real-time stock syncing.<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-674373f elementor-align-justify elementor-widget__width-initial elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"674373f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nail stock accuracy<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-df2fcd7 e-flex e-con-boxed e-con e-parent\" data-id=\"df2fcd7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-af3850c e-con-full e-flex e-con e-child\" data-id=\"af3850c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6694962 elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-video\" data-id=\"6694962\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=-ezRzXe5Sz0&amp;t=1s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28c019c e-con-full e-flex e-con e-child\" data-id=\"28c019c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f41904 elementor-widget elementor-widget-heading\" data-id=\"6f41904\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Choose Innowise as a logistics software development company<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7764dc elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"a7764dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Turn supply chains into a competitive edge with Innowise. Our <span id=\"employers-count\">3,500+<\/span>-strong team designs and builds TMS, WMS, and AI-powered dashboards that link every truck, warehouse, and order in one view in real time. Get instant updates, sharper decisions, airtight compliance, and a system that grows right alongside your business.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7bc5b74 e-flex e-con-boxed e-con e-parent\" data-id=\"7bc5b74\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6babe8d elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"6babe8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our logistics software development roadmap<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b9dccf roadmap-grid-2 elementor-widget elementor-widget-html\" data-id=\"6b9dccf\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"new-steps-container\">\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">Business analysis<\/span>\n            <!--<span class=\"new-step-item-duration\">1-2 hours<\/span>-->\n            <ul class=\"new-step-item-list\">\n                <li>Clarifying requirements<\/li>\n                <li>Examining workflows for inefficiencies<\/li>\n                <li>Evaluating the existing tech ecosystem<\/li>\n            <\/ul>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">Design<\/span>\n            <ul class=\"new-step-item-list\">\n                <li>Preparing software specifications<\/li>\n                <li>Creating wireframes & mockups<\/li>\n                <li>Delivering a proof of concept<\/li>\n            <\/ul>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">Planning<\/span>\n            <ul class=\"new-step-item-list\">\n                <li>Defining scope, deliverables, strategy<\/li>\n                <li>Establishing schedule & budget<\/li>\n                <li>Developing a risk management plan<\/li>\n            <\/ul>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">Development<\/span>\n            <ul class=\"new-step-item-list\">\n                <li>Coding front-end & back-end <\/li>\n                <li>Setting up software integrations<\/li>\n                <li>Conducting code reviews & debugging<\/li>\n            <\/ul>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">Testing & deployment<\/span>\n            <ul class=\"new-step-item-list\">\n                <li>Conducting & automating tests<\/li>\n                <li>Deploying on-premises or in the cloud<\/li>\n                <li>Migrating corporate data securely<\/li>\n            <\/ul>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">Support & maintenance<\/span>\n            <ul class=\"new-step-item-list\">\n                <li>Ongoing maintenance & troubleshooting<\/li>\n                <li>Providing user training & support<\/li>\n                <li>Improving the apps over time<\/li>\n            <\/ul>\n        <\/div>\n    <\/div>\n\n\n\n<\/div>\n\n\n<script>\n    (() => {\n\n        \/\/ number of elements must be at least equal to num of colors to work\n        const colors = [\n            \"#C63031\",\n            \"#CD505D\",\n            \"#D36F89\",\n            \"#DD9ECB\",\n            \"#E4BEF7\",\n            \"#A481BF\",\n        ]\n\n        const desktopFigures = [...document.querySelectorAll(\".roadmap-grid-2 .new-steps-container .figure-container\")]\n\n        desktopFigures.forEach((item, index) => {\n            item.style.setProperty(\"--item-color\", colors[index]);\n            \n            if (index >= 1) {\n                item.style.setProperty(\"--prev-item-color\", colors[index]);\n            }\n        })\n\n    })()\n<\/script>\n\n\n\n\n\n\n\n\n\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c1ff04 e-flex e-con-boxed e-con e-parent\" data-id=\"6c1ff04\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af5719c elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"af5719c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Industries we\u2019ve helped<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebdafc5 elementor-widget elementor-widget-html\" data-id=\"ebdafc5\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n    <div class=\"x-industries__list\">\r\n        <div class=\"x-industries__swiper\">\r\n          <ul class=\"x-industries__list_container swiper-wrapper\">\r\n            <li class=\"swiper-slide active\">Transportation<\/li>\r\n            <li class=\"swiper-slide\">Warehousing<\/li>\r\n            <li class=\"swiper-slide\">E-commerce<\/li>\r\n            <li class=\"swiper-slide\">Healthcare<\/li>\r\n            <li class=\"swiper-slide\">Food & beverage<\/li>\r\n            <li class=\"swiper-slide\">3PL<\/li>\r\n          <\/ul>\r\n        <\/div>\r\n\r\n\r\n\r\n\r\n\r\n        <div class=\"x-industries__navigation\">\r\n            <button class=\"x-industries__navigation-btn\">\r\n                <svg width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n                    <g>\r\n                        <path d=\"M12 4L4 12L12 20\" stroke=\"#2E2E2E\" stroke-width=\"2\" \/>\r\n                        <path d=\"M21 12.0002L4 12.0002\" stroke=\"#2E2E2E\" stroke-width=\"2\" \/>\r\n                    <\/g>\r\n                <\/svg>\r\n            <\/button>\r\n\r\n            <button class=\"x-industries__navigation-btn\">\r\n                <svg width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n                    <path d=\"M13 4L21 12L13 20\" stroke=\"#2E2E2E\" stroke-width=\"2\" \/>\r\n                    <path d=\"M4 12.0002L21 12.0002\" stroke=\"#2E2E2E\" stroke-width=\"2\" \/>\r\n                <\/svg>\r\n            <\/button>\r\n        <\/div>\r\n    <\/div>\r\n\r\n\r\n\r\n\r\n  \r\n  \r\n<script>\r\n\r\n\/\/ document.addEventListener(\"DOMContentLoaded\", function() {\r\n\r\n\r\n\/\/   const xindustriesListItems = document.querySelectorAll('.x-industries__list_container li');\r\n\r\n\r\n  \r\n\/\/   const industriesSlider1 = new Swiper('.x-industries__swiper', {\r\n\/\/     slidesPerView: 'auto',\r\n\/\/     spaceBetween: 24,  \r\n\r\n\r\n\/\/       watchSlidesProgress: true,\r\n\/\/     grabCursor: true,\r\n    \r\n    \r\n          \r\n\/\/   breakpoints: {\r\n\/\/   280: {\r\n\/\/     spaceBetween: 20, \r\n\/\/     },\r\n\r\n\r\n\/\/      820: {\r\n\/\/     spaceBetween: 24, \r\n\/\/     },\r\n\/\/   } \r\n    \r\n\r\n\/\/   });\r\n  \r\n\r\n  \r\n  \r\n\/\/   const industriesSlider2 = new Swiper('.industries__swiper', {\r\n\/\/     slidesPerView: 1,\r\n\/\/   spaceBetween: 24, \r\n\/\/       effect:'fade',\r\n\/\/     grabCursor: true,\r\n\/\/       thumbs: {\r\n\/\/         swiper: industriesSlider1 ,\r\n\/\/       },\r\n\/\/       navigation: {\r\n\/\/         nextEl: \".x-industries__navigation button:nth-child(2)\",\r\n\/\/         prevEl: \".x-industries__navigation button:nth-child(1)\",\r\n\/\/       },\r\n\/\/   });  \r\n    \r\n  \r\n  \r\n  \r\n\/\/ industriesSlider2.on('slideChange', function (data) {\r\n\r\n\/\/ const activeIndex = data.activeIndex;\r\n\r\n    \r\n\/\/ xindustriesListItems.forEach((elem,i)=>{\r\n\/\/          if (activeIndex === i) {\r\n\/\/           elem.classList.add('active');\r\n\/\/         } else {\r\n\/\/           elem.classList.remove('active');\r\n\/\/         }   \r\n\/\/ })\r\n\r\n\r\n\/\/ });  \r\n  \r\n\/\/ });  \r\n\r\n\r\n\r\n\r\ndocument.addEventListener(\"DOMContentLoaded\", function() {\r\n\r\n\r\n  const xindustriesListItems = document.querySelectorAll('.x-industries__list_container li');\r\n  \r\n  const industriesSlider1 = new Swiper('.x-industries__swiper', {\r\n    slidesPerView: 'auto',\r\n    spaceBetween: 24,  \r\n\r\n      watchSlidesProgress: true,\r\n    grabCursor: true,\r\n    \r\n    \r\n          \r\n  breakpoints: {\r\n   280: {\r\n    spaceBetween: 20, \r\n    },\r\n\r\n\r\n     820: {\r\n    spaceBetween: 24, \r\n    },\r\n  } \r\n    \r\n\r\n  });\r\n  \r\n\r\n  \r\n  const industriesSlider2 = new Swiper('.industries__swiper', {\r\n    slidesPerView: 1,\r\n   spaceBetween: 24, \r\n       effect:'fade',\r\n    grabCursor: true,\r\n      thumbs: {\r\n        swiper: industriesSlider1 ,\r\n      },\r\n      navigation: {\r\n        nextEl: \".x-industries__navigation button:nth-child(2)\",\r\n        prevEl: \".x-industries__navigation button:nth-child(1)\",\r\n      },\r\n  });  \r\n    \r\n  \r\n  \r\n  \r\nindustriesSlider2.on('slideChange', function (data) {\r\n\r\nconst activeIndex = data.activeIndex;\r\n\r\n industriesSlider1.slideTo(activeIndex);\r\n \r\n    \r\nxindustriesListItems.forEach((elem,i)=>{\r\n         if (activeIndex === i) {\r\n          elem.classList.add('active');\r\n        } else {\r\n          elem.classList.remove('active');\r\n        }   \r\n}) \r\n\r\n});  \r\n  \r\n});  \r\n  \r\n\r\n <\/script>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5520b0 elementor-widget elementor-widget-html\" data-id=\"c5520b0\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"x-industries__descriptions industries__swiper\">\r\n  <div class=\"swiper-wrapper\">\r\n\r\n    <div class=\"x-industries__descriptions-item swiper-slide swiper-slide-active\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>Transportation & Shipping<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          Slash fuel bills and speed up deliveries by linking dispatchers, drivers, and shippers in one transportation management system. Real-time tracking, auto-planned routes, and instant status updates help you shave fuel costs and hit delivery windows.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Lower fuel costs<\/li>\r\n          <li>Higher on-time delivery rates<\/li>\r\n          <li>Full compliance<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Industry-pic-19.png\" alt=\"Transportation & Shipping\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>Warehousing & Distribution<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          We create warehouse management software that turns scattered stock into a clear snapshot. Live inventory views, guided picking paths, and automatic restocking cut errors, speed up orders, and give you full control across every warehouse.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Fewer picking errors<\/li>\r\n          <li>Better team productivity<\/li>\r\n          <li>Total inventory visibility<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Industry-pic-20.png\" alt=\"Warehousing & Distribution\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>E-commerce & Retail<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          Run every sales channel, online, retail, or marketplace, through one smooth order management system. Features like AI demand forecasts, automated shipping, and simple returns make sure orders fly out the door, shelves stay stocked, and customers stay loyal.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Faster order fulfillment<\/li>\r\n          <li>No overselling or stockouts<\/li>\r\n          <li>Easier returns management<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/02\/Industry-pic-1.png\" alt=\"E-commerce & Retail\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>Healthcare & Pharmaceuticals<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          Keep every vial safe and on the move with live cold-chain monitoring, instant low-stock alerts, and built-in compliance checks. Thanks to custom logistics software development, temperatures stay on target, audits sail through, and life-critical shortages never happen.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Cold-chain visibility<\/li>\r\n          <li>Automated compliance<\/li>\r\n          <li>Real-time low-stock alerts<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/02\/Industry-pic-2.png\" alt=\"Healthcare & Pharmaceuticals\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>Food & Beverage<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          Our T-shaped experts build logistics solutions that keep your perishables farm-fresh with live temperature and expiry tracking, AI route optimization, and instant spoilage alerts. So, you can cut waste, deliver faster, and lock in top-tier food safety.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Reduced spoilage & waste<\/li>\r\n          <li>Optimized fresh deliveries<\/li>\r\n          <li>Higher food safety<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Industry-pic-7.jpg\" alt=\"Food & Beverage\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>3PL & Supply Chain Partners<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          Offer clients multi-client logistics platforms with instant quotes, smart load consolidation, and real-time shipment views. Onboard new accounts faster, pack more freight per trip, and boost margins with transparent service everyone trusts.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Faster client onboarding<\/li>\r\n          <li>Higher profit margins<\/li>\r\n          <li>Full shipment visibility<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Industry-pic-21.png\" alt=\"3PL & Supply Chain Partners\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n  <\/div>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e31893 e-grid e-con-full e-con e-child\" data-id=\"7e31893\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d6d0651 e-con-full e-flex e-con e-child\" data-id=\"d6d0651\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c81dfe img900500 elementor-widget elementor-widget-image\" data-id=\"5c81dfe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1350\" height=\"750\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3.jpg\" class=\"attachment-full size-full wp-image-182131\" alt=\"OUR TEAM\" srcset=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3.jpg 1350w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3-300x167.jpg 300w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3-1024x569.jpg 1024w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3-768x427.jpg 768w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3-18x10.jpg 18w\" sizes=\"(max-width: 1350px) 100vw, 1350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17db413 e-con-full e-flex e-con e-child\" data-id=\"17db413\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-32f194f e-con-full e-flex e-con e-child\" data-id=\"32f194f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4870f0d elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"4870f0d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">In-house talent stretched too thin? <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a15541b elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial tabletmax510 elementor-widget elementor-widget-text-editor\" data-id=\"a15541b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tap our T-shaped developers and get top-tier skills exactly when the pressure\u2019s on.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f1f374 elementor-align-center contact320 elementor-widget elementor-widget-button\" data-id=\"4f1f374\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Add experts fast<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b82454 e-flex e-con-boxed e-con e-parent\" data-id=\"1b82454\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ade9f4 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"4ade9f4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Core technologies we work with<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ee30ef elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"2ee30ef\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n    <div class=\"technologies-content\">\r\n        <div class=\"technologies-content-body\">\r\n            <div class=\"technologies-content-body-menu\">\r\n                <div class=\"technologies-content-body-menu-item technologies_menu clickMenu active\" section=\"1\" content=\"technologies\">Frontend<\/div>\r\n                <div class=\"technologies-content-body-menu-item technologies_menu clickMenu\" section=\"2\" content=\"technologies\">Backend<\/div>\r\n                <div class=\"technologies-content-body-menu-item technologies_menu clickMenu\" section=\"3\" content=\"technologies\">Mobile<\/div>\r\n                <div class=\"technologies-content-body-menu-item technologies_menu clickMenu\" section=\"4\" content=\"technologies\">Clouds<\/div>\r\n                <div class=\"technologies-content-body-menu-item technologies_menu clickMenu\" section=\"5\" content=\"technologies\">ERP & CRM<\/div>\r\n                <div class=\"technologies-content-body-menu-item technologies_menu clickMenu\" section=\"6\" content=\"technologies\">Other<\/div>\r\n            <\/div>\r\n            <div class='technologiesSwiper'>            <div class='swiper-wrapper'>\r\n                \r\n            <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_1 swiper-slide-active\">\r\n                <a href=\"https:\/\/innowise.com\/services\/front-end-development\/\" class=\"technologies-content-body-information-title\">Frontend<\/a>\r\n                \r\n                <div class=\"technologies-content-body-information-items\">\r\n                    <a href='https:\/\/innowise.com\/technologies\/react-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">React<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Default.svg\" alt=\"react\">\r\n                                <\/div>\r\n\r\n                                  \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/angular-development\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Angular<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Angular.svg\" alt=\"\">\r\n                                <\/div>\r\n\r\n                                 \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/vuejs-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Vue.js<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant3.svg\" alt=\"vue\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/javascript-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">JavaScript<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\"  src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/JavaScript.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">TypeScript<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/TypeScript.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    \r\n                    \r\n                    <\/div> \r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_2\">\r\n                <a href=\"https:\/\/innowise.com\/services\/back-end-development\/\" class=\"technologies-content-body-information-title\">Backend<\/a>\r\n                <div class=\"technologies-content-body-information-items\">\r\n                    <a href='https:\/\/innowise.com\/technologies\/java-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Java<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Java-1.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/dot-net-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">.NET<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/NET.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/python-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Python<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant12.svg\" alt=\"\">\r\n                                <\/div>\r\n       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n\t\t\t\t\t<a href='https:\/\/innowise.com\/technologies\/php-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">PHP<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/PHP.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n                        <\/a>\r\n                    \r\n                    <a href='https:\/\/innowise.com\/technologies\/nodejs-development\/' class=\"grid-item\">\r\n                        <div class=\"block-technologies\" >\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Node.js<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant6.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/unity-development\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Unity<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/unity.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/ruby-on-rails-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Ruby<\/div>\r\n                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant8.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                                        <a href=https:\/\/innowise.com\/technologies\/golang-development\/ class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Go<\/div>\r\n             \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant18.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                                        <a href='https:\/\/innowise.com\/technologies\/rust-development\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Rust<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Rust.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                                        <a href='https:\/\/innowise.com\/technologies\/c-plus-plus-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">C\/C++<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/11\/icon-2-1.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>  \r\n                    \r\n                    \r\n                                        <a href='https:\/\/innowise.com\/technologies\/unreal-engine-development\/' class=\"grid-item black\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Unreal Engine<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Unreal-Engine.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>  \r\n                    \r\n                    \r\n                                        <a href='https:\/\/innowise.com\/technologies\/cobol-development\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Cobol<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/cobol.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                    <\/div><\/div>\r\n\r\n            <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_3\">\r\n                <a href=\"https:\/\/innowise.com\/services\/mobile-application-development\/\" class=\"technologies-content-body-information-title\">Mobile<\/a>\r\n                <div class=\"technologies-content-body-information-items\">\r\n                    <a  href='https:\/\/innowise.com\/services\/mobile-application-development\/ios\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">iOS<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant16.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n \r\n                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/services\/mobile-application-development\/android\/' class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Android<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant14.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/flutter-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Flutter<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant11.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                     \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/react-native-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">React Native<\/div>\r\n              \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Default.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                        \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/xamarin-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Xamarin<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/08\/Xamarin.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                                       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/maui-development\/' class=\"grid-item\">\r\n                      <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">.NET MAUI<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/net-maui.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                        \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                \r\n                <\/div>\r\n            <\/div>\r\n  \r\n            \r\n            \r\n            <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_4\">\r\n                <a href=\"https:\/\/innowise.com\/services\/cloud-development\/\" class=\"technologies-content-body-information-title\">Clouds<\/a>\r\n                <div class=\"technologies-content-body-information-items\">\r\n                    <a href='https:\/\/innowise.com\/technologies\/aws\/' class=\"grid-item\">\r\n                    <div class=\"block-technologies\">\r\n                        \r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">AWS<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/AWS.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n\r\n                             \r\n                            <\/div>\r\n                           <\/div>\r\n                        <\/a>\r\n                    \r\n                    <a href='https:\/\/innowise.com\/technologies\/azure\/' class=\"grid-item\">\r\n                      <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Azure<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Microsoft-Azure.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                  \r\n                            <\/div>\r\n                     <\/div>\r\n                    <\/a>\r\n\r\n                    <a href='https:\/\/innowise.com\/technologies\/google-cloud-platform\/' class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">GCP<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Google-Cloud-Platform-GCP.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">DigitalOcean<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/DigitalOcean.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                  \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    \r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Private clouds<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Private-clouds.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                  \r\n                            <\/div>\r\n                        <\/div>\r\n                    \r\n                    <\/div>\r\n                    <\/div>                     \r\n                    \r\n                    \r\n                <\/div>   \r\n                \r\n          <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_5\">\r\n                <span class=\"technologies-content-body-information-title\"><a href=\"https:\/\/innowise.com\/services\/erp\/\" class=\"technologies-content-body-information-title\">ERP<\/a> & <a href=\"https:\/\/innowise.com\/services\/crm\/development\/\" class=\"technologies-content-body-information-title\">CRM<\/a><\/span>\r\n                <div class=\"technologies-content-body-information-items\">\r\n                    <a href='https:\/\/innowise.com\/services\/erp\/sap\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">SAP<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/SAP.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/services\/erp\/microsoft-dynamics-365\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">MS Dynamics 365<\/div>\r\n                                \r\n                    \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Dynamics365.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                     \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/services\/erp\/odoo\/development\/' class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Odoo<\/div>\r\n               \r\n                    \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Odoo.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/services\/crm\/salesforce\/' class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Salesforce<\/div>\r\n               \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/salesforce.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                    \r\n                <\/div>\r\n            <\/div>                \r\n            \r\n            <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_6\">\r\n                <div class=\"technologies-content-body-information-title\">Other<\/div>\r\n                <div class=\"technologies-content-body-information-items\">\r\n                    <div class=\"grid-item\">\r\n                        <a href='https:\/\/innowise.com\/services\/embedded-software-development\/' class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Embedded<\/div>\r\n                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Embedded.svg\" alt=\"\">           <\/div>\r\n                                \r\n                                  \r\n                  \r\n                            <\/div>\r\n                        <\/div>\r\n                        <\/a>\r\n                    <\/div>\r\n                    \r\n                    <a href='https:\/\/innowise.com\/services\/mainframe-support-and-maintenance\/' class=\"grid-item\">\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Mainframes<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Mainframes.svg\" alt=\"\">             <\/div>\r\n                                \r\n                                  \r\n                                  \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/services\/business-intelligence\/' class=\"grid-item\">\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">BI tools<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/BI-tools.svg\" alt=\"\">           <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/industries\/ecommerce\/' class=\"grid-item\">\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">eCommerce platforms<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                   <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/eCommerce-platforms.svg\" alt=\"\">              <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/services\/cms\/' class=\"grid-item\">\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">CMS<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/CMS.svg\" alt=\"\">             <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <\/a>\r\n                    \r\n                <\/div>\r\n            <\/div>\r\n            \r\n\r\n            <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n<script>\r\n\r\ndocument.addEventListener('DOMContentLoaded', () => {\r\n    \r\n  const technologiesSwiper = new Swiper('.technologiesSwiper', {\r\n      effect:'fade',\r\n    slidesPerView: 1,\r\n   spaceBetween: 24, \r\n\r\n    allowTouchMove:false,   \r\n       \r\n  });  \r\n    \r\n\r\nconst technologiesListItems = document.querySelectorAll(\r\n  '.technologies-content-body-menu-item'\r\n);\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\n\r\ntechnologiesListItems.forEach((listItem, index, arr) => {\r\n    \r\n  listItem.addEventListener('click', () => {\r\n    arr.forEach((item,i) => {\r\n      if (item === listItem) {\r\n        item.classList.add('active');\r\n        technologiesSwiper.slideTo(i);\r\n      } else {\r\n        item.classList.remove('active');\r\n      }\r\n    });\r\n    \r\n  });\r\n});\r\n\r\n\r\n\r\n\r\n\r\n});\r\n\r\n<\/script>\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9605c5e rating-table-topRated elementor-hidden-desktop elementor-widget elementor-widget-n-accordion\" data-id=\"9605c5e\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1570\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1570\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Frontend <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1570\" class=\"elementor-element elementor-element-fe44268 e-con-full e-flex e-con e-child\" data-id=\"fe44268\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1d953b elementor-widget elementor-widget-html\" data-id=\"a1d953b\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div class=\"technologies-content-body-information-items\">\r\n                    <a href='https:\/\/innowise.com\/technologies\/react-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">React<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Default.svg\" alt=\"react\">\r\n                                <\/div>\r\n\r\n                                  \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/angular-development\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Angular<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Angular.svg\" alt=\"\">\r\n                                <\/div>\r\n\r\n                                 \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/vuejs-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Vue.js<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant3.svg\" alt=\"vue\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/javascript-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">JavaScript<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\"  src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/JavaScript.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">TypeScript<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/TypeScript.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    \r\n                    \r\n                    <\/div> \r\n                <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1571\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1571\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Backend <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1571\" class=\"elementor-element elementor-element-0ffb068 e-con-full e-flex e-con e-child\" data-id=\"0ffb068\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b249816 elementor-widget elementor-widget-html\" data-id=\"b249816\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div class=\"technologies-content-body-information-items\">\r\n                    <a href='https:\/\/innowise.com\/technologies\/java-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Java<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Java-1.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/dot-net-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">.NET<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/NET.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/python-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Python<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant12.svg\" alt=\"\">\r\n                                <\/div>\r\n       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n\t\t\t\t\t<a href='https:\/\/innowise.com\/technologies\/php-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">PHP<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/PHP.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n                        <\/a>\r\n                    \r\n                    <a href='https:\/\/innowise.com\/technologies\/nodejs-development\/' class=\"grid-item\">\r\n                        <div class=\"block-technologies\" >\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Node.js<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant6.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/unity-development\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Unity<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/unity.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href='https:\/\/innowise.com\/technologies\/ruby-on-rails-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Ruby<\/div>\r\n                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant8.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                                        <a href=https:\/\/innowise.com\/technologies\/golang-development\/ class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Go<\/div>\r\n             \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant18.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                                        <a href='https:\/\/innowise.com\/technologies\/rust-development\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Rust<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Rust.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                                        <a href='https:\/\/innowise.com\/technologies\/c-plus-plus-development\/' class=\"grid-item\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">C\/C++<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/11\/icon-2-1.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>  \r\n                    \r\n                    \r\n                                        <a href='https:\/\/innowise.com\/technologies\/unreal-engine-development\/' class=\"grid-item black\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Unreal Engine<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Unreal-Engine.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>  \r\n                    \r\n                    \r\n                                        <a href='https:\/\/innowise.com\/technologies\/cobol-development\/' class=\"grid-item black\">\r\n                        <div  class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Cobol<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/cobol.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1572\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1572\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Mobile <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1572\" class=\"elementor-element elementor-element-ad605d4 e-con-full e-flex e-con e-child\" data-id=\"ad605d4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcb5277 elementor-widget elementor-widget-html\" data-id=\"fcb5277\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"technologies-content-body-information-items\">\r\n                    <a href=\"https:\/\/innowise.com\/services\/mobile-application-development\/ios\/\" class=\"grid-item black\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">iOS<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant16.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n \r\n                \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/services\/mobile-application-development\/android\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Android<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant14.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/technologies\/flutter-development\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Flutter<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant11.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                     \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/technologies\/react-native-development\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">React Native<\/div>\r\n              \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Default.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                        \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/technologies\/xamarin-development\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Xamarin<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/08\/Xamarin.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                                       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/technologies\/maui-development\/\" class=\"grid-item\">\r\n                      <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">.NET MAUI<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/net-maui.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                        \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                \r\n                <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1573\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1573\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Clouds <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1573\" class=\"elementor-element elementor-element-9235463 e-con-full e-flex e-con e-child\" data-id=\"9235463\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5cd9860 elementor-widget elementor-widget-html\" data-id=\"5cd9860\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"technologies-content-body-information-items\">\r\n                    <a href=\"https:\/\/innowise.com\/technologies\/aws\/\" class=\"grid-item\">\r\n                    <div class=\"block-technologies\">\r\n                        \r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">AWS<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/AWS.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n\r\n                             \r\n                            <\/div>\r\n                           <\/div>\r\n                        <\/a>\r\n                    \r\n                    <a href=\"https:\/\/innowise.com\/technologies\/azure\/\" class=\"grid-item\">\r\n                      <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Azure<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Microsoft-Azure.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                  \r\n                            <\/div>\r\n                     <\/div>\r\n                    <\/a>\r\n\r\n                    <a href=\"https:\/\/innowise.com\/technologies\/google-cloud-platform\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">GCP<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Google-Cloud-Platform-GCP.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">DigitalOcean<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/DigitalOcean.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                  \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    \r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Private clouds<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Private-clouds.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                    \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                  \r\n                            <\/div>\r\n                        <\/div>\r\n                    \r\n                    <\/div>\r\n                    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1574\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1574\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> ERP &amp; CRM <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1574\" class=\"elementor-element elementor-element-0683a5d e-con-full e-flex e-con e-child\" data-id=\"0683a5d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54fa073 elementor-widget elementor-widget-html\" data-id=\"54fa073\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"technologies-content-body-information-items\">\r\n                    <a href=\"https:\/\/innowise.com\/services\/erp\/sap\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">SAP<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/SAP.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/services\/erp\/microsoft-dynamics-365\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">MS Dynamics 365<\/div>\r\n                                \r\n                    \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Dynamics365.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                     \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/services\/erp\/odoo\/development\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Odoo<\/div>\r\n               \r\n                    \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Odoo.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n                       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/services\/crm\/salesforce\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Salesforce<\/div>\r\n               \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/salesforce.svg\" alt=\"\">\r\n                                <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                       \r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/a>\r\n                    \r\n                    \r\n                <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1575\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1575\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Other <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1575\" class=\"elementor-element elementor-element-22f3a88 e-con-full e-flex e-con e-child\" data-id=\"22f3a88\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8610aad elementor-widget elementor-widget-html\" data-id=\"8610aad\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"technologies-content-body-information-items\">\r\n                    <div class=\"grid-item\">\r\n                        <a href=\"https:\/\/innowise.com\/services\/embedded-software-development\/\" class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Embedded<\/div>\r\n                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Embedded.svg\" alt=\"\">           <\/div>\r\n                                \r\n                                  \r\n                  \r\n                            <\/div>\r\n                        <\/div>\r\n                        <\/a>\r\n                    <\/div>\r\n                    \r\n                    <a href=\"https:\/\/innowise.com\/services\/mainframe-support-and-maintenance\/\" class=\"grid-item\">\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">Mainframes<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Mainframes.svg\" alt=\"\">             <\/div>\r\n                                \r\n                                  \r\n                                  \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/services\/business-intelligence\/\" class=\"grid-item\">\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">BI tools<\/div>\r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/BI-tools.svg\" alt=\"\">           <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/industries\/ecommerce\/\" class=\"grid-item\">\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">eCommerce platforms<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                   <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/eCommerce-platforms.svg\" alt=\"\">              <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <\/a>\r\n                    <a href=\"https:\/\/innowise.com\/services\/cms\/\" class=\"grid-item\">\r\n                    <div class=\"grid-item\">\r\n                        <div class=\"block-technologies\">\r\n                            <div class=\"block-technologies-text\">\r\n                                <div class=\"block-technologies-text-title\">CMS<\/div>\r\n                                \r\n                                \r\n                            <\/div>\r\n                            <div class=\"block-technologies-addition\">\r\n                                <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/CMS.svg\" alt=\"\">             <\/div>\r\n                                \r\n                                  \r\n                                  \r\n                                            \r\n                                            \r\n\r\n                                            \r\n                                            \r\n\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <\/a>\r\n                    \r\n                <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd6d13b e-flex e-con-boxed e-con e-parent\" data-id=\"cd6d13b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3683b4c elementor-widget elementor-widget-heading\" data-id=\"3683b4c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What our customers think<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9795c8d elementor-widget elementor-widget-html\" data-id=\"9795c8d\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"c-section__background c-section__background\">\r\n  <div class=\"c-section__container p-mad-testimonials__section-container\">\r\n    <div class=\"c-section__body\">\r\n      <div class=\"p-mad-testimonials__swiper\">\r\n        <div class=\"swiper\">\r\n          <div class=\"swiper-wrapper\">\r\n\r\n            <div class=\"swiper-slide p-mad-testimonial\">\r\n              <div class=\"p-mad-testimonial__cite-author\">\r\n                <div class=\"p-mad-testimonial__author\">\r\n                  <span class=\"p-mad-testimonial__author-name\">Dr. Udo Richter<\/span>\r\n                  <span>Director<\/span>\r\n                  <span>n:aip<\/span>\r\n                <\/div>\r\n                <div class=\"p-mad-testimonial__company-icon-wrapper\">\r\n                  <img decoding=\"async\" class=\"p-mad-testimonial__company-icon\"\r\n                       src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/n_aip.png\" \r\n                       alt=\"Healthcare company logo\">\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"p-mad-testimonial__cite-details\">\r\n                <p class=\"p-mad-testimonial__cite\">\u201cInnowise was selected due to its extensive experience of developing complex medical solutions. They managed to quickly and effectively put together a team of IT-specialists. Innowise is characterized by efficient and professional organization of its operation practices.\u201d<\/p>\r\n                <ul class=\"p-mad-testimonial__details\">\r\n                  <li>\r\n                      <span class=\"p-mad-testimonial__details-term\">Industry<\/span>\r\n                      <span class=\"p-mad-testimonial__details-desc\">Healthcare<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Team size<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">4 specialists<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Duration<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">60+ months<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Services<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">Software modernization<\/span>\r\n                  <\/li>\r\n                <\/ul>\r\n              <\/div>\r\n            <\/div>\r\n\r\n            <div class=\"swiper-slide p-mad-testimonial\">\r\n              <div class=\"p-mad-testimonial__cite-author\">\r\n                <div class=\"p-mad-testimonial__author\">\r\n                  <span class=\"p-mad-testimonial__author-name\">Laurynas Savickas<\/span>\r\n                  <span>CEO<\/span>\r\n                  <span>Intervilza JSC\r\n\r\n<\/span>\r\n                <\/div>\r\n                <div class=\"p-mad-testimonial__company-icon-wrapper\">\r\n                  <img decoding=\"async\" class=\"p-mad-testimonial__company-icon\"\r\n                       src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/InterVilza.png\" \r\n                       alt=\"Intervilza JSC logo\">\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"p-mad-testimonial__cite-details\">\r\n                <p class=\"p-mad-testimonial__cite\">\u201cWorking with Innowise, I appreciate their customer-centric approach and care for even the smallest detail. Our company received exactly what we'd been looking for and managed to save a considerable part of our budget for other activities.\u201d<\/p>\r\n                <ul class=\"p-mad-testimonial__details\">\r\n                  <li>\r\n                      <span class=\"p-mad-testimonial__details-term\">Industry<\/span>\r\n                      <span class=\"p-mad-testimonial__details-desc\">Manufacturing\r\n\r\n<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Team size<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">3 specialists<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Duration<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">3 months<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Services<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">IT outsourcing, custom development, 3D design<\/span>\r\n                  <\/li>\r\n                <\/ul>\r\n              <\/div>\r\n            <\/div>\r\n\r\n            <div class=\"swiper-slide p-mad-testimonial\">\r\n              <div class=\"p-mad-testimonial__cite-author\">\r\n                <div class=\"p-mad-testimonial__author\">\r\n                  <span class=\"p-mad-testimonial__author-name\">Joakim Rosen<\/span>\r\n                  <span>Lead Developer<\/span>\r\n                  <span>YouWish<\/span>\r\n                <\/div>\r\n                <div class=\"p-mad-testimonial__company-icon-wrapper\">\r\n                  <img decoding=\"async\" class=\"p-mad-testimonial__company-icon\"\r\n                       src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/03\/youwish.no_.png\" \r\n                       alt=\"YouWish AS logo\">\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"p-mad-testimonial__cite-details\">\r\n                <p class=\"p-mad-testimonial__cite\">\u201cInnowise has completed many projects and consistently performs well on their tasks. Their results-driven approach allows them to quickly scale their efforts depending on the required deliverables.\u201d<\/p>\r\n                <ul class=\"p-mad-testimonial__details\">\r\n                    <li>\r\n                      <span class=\"p-mad-testimonial__details-term\">Industry<\/span>\r\n                      <span class=\"p-mad-testimonial__details-desc\">Consumer products<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Team size<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">4 specialists<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Duration<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">28+ months<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Services<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">Staff augmentation<\/span>\r\n                  <\/li>\r\n                <\/ul>\r\n              <\/div>\r\n            <\/div>\r\n\r\n          <\/div>\r\n\r\n          <!-- Swiper Pagination -->\r\n          <div class=\"swiper-pagination\"><\/div>\r\n\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\r\n\r\n\r\n\r\n  \r\n  <script>\r\n  const options = {\r\n    grabCursor: true,\r\n    slidesPerView: 'auto',\r\n    spaceBetween: 20,\r\n    pagination: {\r\n      el: '.p-mad-testimonials__swiper .swiper-pagination',\r\n      clickable:true,\r\n    },\r\n    breakpoints: {\r\n       200: {\r\n        spaceBetween: 20\r\n       },\r\n       768: {\r\n        spaceBetween: 40\r\n       },\r\n      },\r\n  };\r\n  \r\n  let customerReviewsSwiper = new Swiper(\r\n    '.p-mad-testimonials__swiper .swiper',\r\n    options,\r\n  );\r\n  \r\n  customerReviewsSwiper.autoplay.stop();\r\n  \r\n  <\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4093847 e-flex e-con-boxed e-con e-parent\" data-id=\"4093847\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aba4ea0 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"aba4ea0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34e9fdb e-con-full e-grid e-con e-child\" data-id=\"34e9fdb\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-67b143f e-con-full e-flex e-con e-child\" data-id=\"67b143f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-275afce faq elementor-widget elementor-widget-n-accordion\" data-id=\"275afce\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4120\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4120\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Does Innowise develop SaaS applications for logistics and transportation? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M19 8h2v24h-2z\"><\/path><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4120\" class=\"elementor-element elementor-element-f82c297 e-con-full e-flex e-con e-child\" data-id=\"f82c297\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e71650 elementor-widget elementor-widget-html\" data-id=\"5e71650\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='content'>\n <p>Absolutely! As a part of our logistics software development services, we build cloud-native SaaS platforms tailored for logistics and transportation, so you get real-time shipment tracking, fleet management, and route optimization without sweating over on-prem hardware or tangled installations.\n<\/p>   \n<\/div> \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4121\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4121\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> What is the average time for logistics software development? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M19 8h2v24h-2z\"><\/path><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4121\" class=\"elementor-element elementor-element-840dc84 e-con-full e-flex e-con e-child\" data-id=\"840dc84\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4309e73 elementor-widget elementor-widget-html\" data-id=\"4309e73\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='content'>\n <p>You can generally see your logistics solution go live in about 3\u20136 months. But if you\u2019re after deep integrations, advanced analytics, or large-scale rollouts, the timeline can stretch to 6\u201312 months or even more. After diving into your requirements, team size, and project scope, our team maps out a rock-solid plan, so you know exactly when you\u2019ll see results.\n<\/p>   \n<\/div> \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4122\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4122\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Can you upgrade my existing logistics software? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M19 8h2v24h-2z\"><\/path><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4122\" class=\"elementor-element elementor-element-610ab94 e-flex e-con-boxed e-con e-child\" data-id=\"610ab94\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86d6534 elementor-widget elementor-widget-html\" data-id=\"86d6534\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='content'>\n <p>Sure. First, our experts audit your current system to spot performance bottlenecks, feature gaps, and integration issues. Then we roll out targeted upgrades like faster performance, mobile access, and fresh APIs with minimal downtime. That way, your operations keep humming and your customers never miss a beat.<\/p>   \n<\/div> \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4123\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4123\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> How do logistics software development services benefit businesses? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M19 8h2v24h-2z\"><\/path><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4123\" class=\"elementor-element elementor-element-bcb048b e-flex e-con-boxed e-con e-child\" data-id=\"bcb048b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-022d3a7 elementor-widget elementor-widget-html\" data-id=\"022d3a7\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='content'>\n <p>Logistics and transportation software development helps supercharge operations, slash costs, and boost efficiency across the board. Features like real-time tracking, automated workflows, and smart route planning mean tighter inventory control, faster deliveries, and happier customers. This way, you move quicker, spend less, and keep your service on point.<\/p>   \n<\/div> \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4124\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4124\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Is logistics software suitable for my business size? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M19 8h2v24h-2z\"><\/path><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4124\" class=\"elementor-element elementor-element-1206162 e-flex e-con-boxed e-con e-child\" data-id=\"1206162\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b95ba6 elementor-widget elementor-widget-html\" data-id=\"2b95ba6\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='content'>\n <p>Logistics software fits companies of every size. Whether you\u2019re a lean startup, a growing SMB, or a global enterprise, the platform scales right along with your volumes. Our logistics software development company tunes functionality and pricing to match your needs, so you only pay for the capacity you use and skip the extras you don\u2019t.<\/p>   \n<\/div> \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4125\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4125\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> How can IT solutions for the logistics industry improve supply chain transparency? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" fill=\"none\"><path fill=\"#C63031\" d=\"M19 8h2v24h-2z\"><\/path><path fill=\"#C63031\" d=\"M8 21v-2h24v2z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4125\" class=\"elementor-element elementor-element-6dfc1aa e-flex e-con-boxed e-con e-child\" data-id=\"6dfc1aa\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1f3f92 elementor-widget elementor-widget-html\" data-id=\"d1f3f92\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class='content'>\n <p>Logistics software solutions light up every link of your supply chain in real time. GPS, RFID, and IoT sensors stream live location and condition data into cloud dashboards, while smart analytics flag bottlenecks before they snowball. Drivers, dispatchers, and partners all see the same feed, jump on issues instantly, and keep goods moving.<\/p>   \n<\/div> \n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Does Innowise develop SaaS applications for logistics and transportation?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Absolutely! As a part of our logistics software development services, we build cloud-native SaaS platforms tailored for logistics and transportation, so you get real-time shipment tracking, fleet management, and route optimization without sweating over on-prem hardware or tangled installations.\"}},{\"@type\":\"Question\",\"name\":\"What is the average time for logistics software development?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"You can generally see your logistics solution go live in about 3\\u20136 months. But if you\\u2019re after deep integrations, advanced analytics, or large-scale rollouts, the timeline can stretch to 6\\u201312 months or even more. After diving into your requirements, team size, and project scope, our team maps out a rock-solid plan, so you know exactly when you\\u2019ll see results.\"}},{\"@type\":\"Question\",\"name\":\"Can you upgrade my existing logistics software?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Sure. First, our experts audit your current system to spot performance bottlenecks, feature gaps, and integration issues. Then we roll out targeted upgrades like faster performance, mobile access, and fresh APIs with minimal downtime. That way, your operations keep humming and your customers never miss a beat.\"}},{\"@type\":\"Question\",\"name\":\"How do logistics software development services benefit businesses?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Logistics and transportation software development helps supercharge operations, slash costs, and boost efficiency across the board. Features like real-time tracking, automated workflows, and smart route planning mean tighter inventory control, faster deliveries, and happier customers. This way, you move quicker, spend less, and keep your service on point.\"}},{\"@type\":\"Question\",\"name\":\"Is logistics software suitable for my business size?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Logistics software fits companies of every size. Whether you\\u2019re a lean startup, a growing SMB, or a global enterprise, the platform scales right along with your volumes. Our logistics software development company tunes functionality and pricing to match your needs, so you only pay for the capacity you use and skip the extras you don\\u2019t.\"}},{\"@type\":\"Question\",\"name\":\"How can IT solutions for the logistics industry improve supply chain transparency?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Logistics software solutions light up every link of your supply chain in real time. GPS, RFID, and IoT sensors stream live location and condition data into cloud dashboards, while smart analytics flag bottlenecks before they snowball. Drivers, dispatchers, and partners all see the same feed, jump on issues instantly, and keep goods moving.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ffd3f6 e-con-full e-flex e-con e-child\" data-id=\"0ffd3f6\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0e8ea5a e-con-full maxHeight516 e-flex e-con e-child\" data-id=\"0e8ea5a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb3c5fd elementor-widget elementor-widget-image\" data-id=\"eb3c5fd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/10\/Customer-service.svg\" class=\"attachment-full size-full wp-image-173854\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-33dfefa e-con-full e-flex e-con e-child\" data-id=\"33dfefa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c27a823 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"c27a823\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Feel free to book a call and get all the answers you need.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95d5e2c elementor-widget__width-inherit ctaSecond elementor-widget-tablet__width-initial elementor-widget elementor-widget-button\" data-id=\"95d5e2c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book a call<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a6e0c4 e-flex e-con-boxed e-con e-parent\" data-id=\"3a6e0c4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ea30c3 elementor-widget elementor-widget-shortcode\" data-id=\"9ea30c3\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f100240-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"100240\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/sv\/wp-json\/wp\/v2\/pages\/158736#wpcf7-f100240-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"100240\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f100240-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<style>\n.mailToContact br:nth-child(2){\ndisplay:none;\n}\n#form-templates .contact__info {\n  background-color: #f4f4f4;\n  padding: 70px 44px 70px 50px;\n  position: relative;\n  max-width: 540px;\n  width: 100%;\nborder: 1px solid #AEB1B7;\n}\n\n#form-templates .contact__info-background {\n  z-index: -1;\n  position: absolute;\n  top: 20px;\n  left: 20px;\n  width: 100%;\n  height: 100%;\n  border: 1px dashed #ef4557;\n}\n\n\n#form-templates .new-container{\ndisplay: flex;\njustify-content: space-between;\nflex-wrap: wrap;\n}\n\n\n#form-templates{\npadding: 100px 15px 100px 15px;        \n}\n\n#form-templates .contact__info-heading {\n  font-family: 'Sora' !important;\n  font-style: normal !important;\n  font-weight: 400 !important;\n  font-size: 36px !important;\n  line-height: 46px !important;\n  color: #2E2E2E !important;\n   margin-bottom: 60px !important;\n\n}\n\n\n#form-templates .message label{\ncolor: #585858 !important;   \n}\n\n.elementor-widget-container.form-template h2,.elementor-widget-container.form-template h1{\n font-size: 60px !important;\n  line-height: 70px !important;\n  font-family: \"Sora\", Sans-serif;\n  font-weight: 400;\n  margin: 0;  \n  margin-bottom: 20px;\n}\n\n\n\n\n.elementor-widget-container.form-template p{\n  font-family: \"Karla\", Sans-serif;\n  font-size: 22px;\n  font-weight: 400;\n  line-height: 28px;\n  color: var( --e-global-color-primary );\n  max-width: 700px;\n  margin: 0; \n  margin-bottom: 40px;\n} \n  \n\n\n.new-container #spinner{\nwidth: 50%;\nmax-width: 700px;\n}\n\n\n#form-templates .new-container #spinner div.contact-us__wrapper:nth-child(6){\ngap:30px; \n    \n}\n\n\n#form-templates .contact__info-heading {\n  margin-bottom: 67px;\n  font-size: 36px;\n  font-family: karla;\n  color:  #2E2E2E;\n\n  line-height: 49px;\n}\n\n#form-templates .contact__info-steps {\n  display: flex;\n  flex-direction: column;\n  max-width: 425x;\n  row-gap: 20px;\n  border-left: 1px solid #2e2e2e;\n}\n\n#form-templates .contact__info-block {\n  position: relative;\n  padding-left: 45px;\n}\n\n#form-templates .contact__info-block:last-child {\n  box-shadow: -1px 0 0 1px #f4f4f4;\n}\n\n#form-templates .contact__info-step {\n  position: absolute;\n  border: 1px solid #2e2e2e;\n  width: 40px;\n  height: 40px;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  border-radius: 20px;\n  left: -20px;\n  top: -8px;\n  background-color: #F4F4F4;\n  color:  #2E2E2E;\n\nfont-family: Karla;\nfont-weight: 700;\nfont-size: 18px;\nline-height: 28px;\n\n}\n\n.elementor-widget-global .contact__info-step {\n        color:  #2E2E2E;\n}\n\n#form-templates .contact__info-text {\n  margin: 0;\n  font-size: 16px;\n  line-height: 26px;\n  color: #2E2E2E;\n  font-family: karla;\n\n  width: 100%;\n}\n\n\n#form-templates .contact-us__send{\nflex-shrink: 0;\nmargin-top:0;\n}\n\n\n\n@media screen and (max-width: 1279px) {\n    .new-container #spinner{\n        width: 100%;\n        max-width:100%;\n        margin-bottom:40px;\n    }\n    \n\n    .new-container .contact__info {\n        max-width: 700px !important;\n    }\n    \n}\n\n\n@media screen and (max-width: 1279px) {\n#form-templates{\npadding: 60px 15px 70px 15px;     \n}\n}\n\n\n\n@media screen and (max-width: 767px) {\n\n#form-templates .new-container #spinner div.contact-us__wrapper:nth-child(6){\ngap:20px; \n \n}\n\n\n  #form-templates .contact__info {\n    padding: 20px 20px 40px 40px;\n    margin: 0 auto;\n  }\n\n\n#form-templates{\npadding: 40px 15px 50px 15px;  \n    \n}\n\n  \n   .new-container #spinner{\n       \n    margin-bottom:30px;   \n   }\n   \n   \n   .elementor-widget-container.form-template h2,.elementor-widget-container.form-template h1{\n   font-size: 32px !important;\n    line-height: 42px !important;    \n   }\n   \n   \n   .elementor-widget-container.form-template p{\n       \n    font-size: 16px;\n    line-height: 20px;  \n    margin-bottom: 30px;\n \n       \n   }\n   \n   #form-templates .contact__info-heading{\n   font-size: 24px !important;\n    line-height: 49px !important;    \n       \n   }\n   \n\n.mailToContact{\nmargin-top: 10px !important;        \n}\n\n   \n\n  #form-templates .contact__info-heading {\n    font-size: 24px;\n    margin-bottom: 37px;\n  }\n\n  #form-templates .contact__info-background {\n    top: 10px;\n    left: 10px;\n  }\n\n  #form-templates .contact__info-text {\n    font-size: 12px;\n    line-height: 20px;\n  }\n  \n  \n  #form-templates .contact__info-heading {\n   margin-bottom: 35px !important;\n\n}\n\n}\n\n@media (max-width: 767px) {\n    .mailToContact {\n        max-width: 100%;\n    }\n}\n<\/style>\n\n<script>\nwindow.addEventListener('hashchange',function(e){if(window.history.pushState){window.history.pushState('','\/',window.location.pathname)}else{window.location.hash=''}})\n<\/script>\n\n\n<div id=\"form-templates\">\n<div class=\"elementor-widget-container form-template\">\n<a name=\"contact-form\"><\/a>\n<h2>Contact us<\/h2>\n<p><a id=\"calendlylink\" style=\"color: #c63031; border-bottom: 1px solid #c63031; padding: 0;\">Book a call<\/a> or fill out the form below and we\u2019ll get back to you once we\u2019ve processed your request.<\/p>\n<\/div>\n\n<div class=\"new-container\">\n\n\n<div class=\"contact-us__main\" id=\"spinner\" data-no-defer=\"1\">\n\n<div class=\"contact-us__wrapper\">\n\n<div class=\"name\">\n<label>Name<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"field_name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required contact-us__name\" id=\"contact-name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name*\" value=\"\" type=\"text\" name=\"field_name\" \/><\/span>\n<\/div>\n\n<div class=\"company\">\n<label>Company<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required contact-us__company\" id=\"contact-company\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company*\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n<\/div>\n\n<\/div>\n\n<div class=\"contact-us__wrapper\">\n\n<div class=\"email\">\n<label>Email<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email contact-us__email\" id=\"contact-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Corporate email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n<\/div>\n\n<div class=\"phone\">\n<label>Phone<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel contact-us__phone\" id=\"contact-phone\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone*\" value=\"\" type=\"tel\" name=\"tel\" \/><\/span>\n<\/div>\n\n<\/div>\n<div class=\"contact-us__wrapper subj\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-recipient\"><select class=\"wpcf7-form-control wpcf7-select\" id=\"form-field-subj_js\" aria-invalid=\"false\" name=\"your-recipient\"><option value=\"\">Subject*<\/option><option value=\"IT staff augmentation\">IT staff augmentation<\/option><option value=\"Turnkey product development\">Turnkey product development<\/option><option value=\"Support and enhancement\">Support and enhancement<\/option><option value=\"Careers\">Careers<\/option><option value=\"Other\">Other<\/option><\/select><\/span>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"form-field-budget_js\"><select class=\"wpcf7-form-control wpcf7-select\" id=\"form-field-budget_js\" aria-invalid=\"false\" name=\"form-field-budget_js\"><option value=\"\">Project budget<\/option><option value=\"Under $15K\">Under $15K<\/option><option value=\"$15K-$30K\">$15K-$30K<\/option><option value=\"$30K-$100K\">$30K-$100K<\/option><option value=\"$100K-$250K\">$100K-$250K<\/option><option value=\"$250K-$500K\">$250K-$500K<\/option><option value=\"More than $500K\">More than $500K<\/option><\/select><\/span>\n\n<\/div>\n\n\n<div class=\"message\">\n<label>Message<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"1\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required contact-us__message\" id=\"contact-message\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Describe your needs in detail*\" name=\"message\"><\/textarea><\/span>\n<\/div>\n\n<div class=\"atvoice-wrap\">\n\n<div class=\"voice-wrap\">\n<span id=\"voice-mut\" class=\"voicetext\">Send us a voice message<\/span>\n         <div class=\"qc_voice_audio_wrapper\">\n            <div class=\"qc_voice_audio_container\">\n                <div class=\"qc_voice_audio_upload_main\" id=\"qc_audio_main\">\n                    <a class=\"qc_audio_record_button\" id=\"qc_audio_record\" href=\"#\" aria-label=\"Record an audio message\">\n                        <span class=\"dashicons dashicons-microphone\"><\/span> \u00a0<\/a> \n                <\/div>\n\n                <div class=\"qc_voice_audio_recorder\" id=\"qc_audio_recorder\" style=\"display:none\">\n\n                <\/div>\n                <div class=\"qc_voice_audio_display\" id=\"qc_audio_display\"  style=\"display:none\">\n                    <audio id=\"qc-audio\" controls src=\"\"><\/audio>\n                    <span title=\"Remove and back to main upload screen.\" class=\"qc_audio_remove_button dashicons dashicons-trash\"><\/span>\n                <\/div>\n            <\/div>\n            <input type=\"hidden\" value=\"\" name=\"qcwpvoicemessage\" id=\"qc_audio_url\" \/>\n        <\/div>\n        \n<\/div>\n\n\n<div class=\"attach-wrap\">\n<span class=\"voicetext\">Attach documents<\/span>\n\n<div class='attachment'>\n\n<div class=\"downloaded\">\n<span><\/span>\n<div class=\"deleteFile\"><\/div>\n<\/div>\n\n<div class=\"attachmentButton\" onclick=\"(function cl(e){if(e.target.nodeName == 'DIV'){e.target.parentNode.children[1].children[0].click(); }})(arguments[0]);\">\n\n<div class=\"innerText\">Upload file<\/div>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"att-files\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.png,.jpeg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"att-files\" \/><\/span>\n\n<div class=\"tip\" onclick=\"event.stopPropagation()\">\n<p>You can attach 1 file up to 2MB. Valid file formats: pdf, jpg, jpeg, png.<\/p>\n<\/div>\n\n<\/div>\n\n<\/div>\n\n<\/div>\n\n\n\n<\/div>\n\n<div class=\"contact-us__wrapper\"> \n<p class=\"pp\">By clicking Send, you consent to Innowise processing your personal data per our<a href=\"\/privacy-notice\/\"> Privacy Policy <\/a>to provide you with relevant information. By submitting your phone number, you agree that we may contact you via voice calls, SMS, and messaging apps. Calling, message, and data rates may apply.<\/p>\n\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"scoring_point\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmCampaign\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmContent\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmMedium\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmSource\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmTerm\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"location\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"city\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"ip\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"Summ\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"gclid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"rating\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"urlCompany\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"urlWithParams\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"audioMessageLink\" \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner contact-us__send\" id=\"contact-send-button\" type=\"submit\" value=\"Send\" \/>\n<\/div>\n\n<div class='mailToContact'>You can also send us your request <\/br>to <a href=\"mailto:contact@innowise.com\">contact@innowise.com<\/a><\/div>\n\n<\/div>\n\n<div class=\"elementor-widget-container\" style=\"z-index:1;\">\n<div class=\"contact__info\">\n  <div class=\"contact__info-background\"><\/div>\n  <div class=\"contact__info-heading\">What happens next?<\/div>\n  <div class=\"contact__info-steps\">\n\n    <div class=\"contact__info-block\">\n      <div class=\"contact__info-step\">1<\/div>\n      <p class=\"contact__info-text\">Once we\u2019ve received and processed your request, we\u2019ll get back to you to detail your\n        project needs and sign an NDA to ensure confidentiality.<\/p>\n    <\/div>\n\n    <div class=\"contact__info-block\">\n      <div class=\"contact__info-step\">2<\/div>\n      <p class=\"contact__info-text\">After examining your wants, needs, and expectations, our team will devise a project\n        proposal with the scope of work, team size, time, and cost estimates.<\/p>\n    <\/div>\n\n    <div class=\"contact__info-block\">\n      <div class=\"contact__info-step\">3<\/div>\n      <p class=\"contact__info-text\">We\u2019ll arrange a meeting with you to discuss the offer and nail down the details.<\/p>\n    <\/div>\n\n    <div class=\"contact__info-block\">\n      <div class=\"contact__info-step\">4<\/div>\n      <p class=\"contact__info-text\">Finally, we\u2019ll sign a contract and start working on your project right away.<\/p>\n    <\/div>\n  <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\n<\/div>\n\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"other_services_container\">[need_other_services_v2]<\/div><script>\n            jQuery( document ).ready(function($) {\n                $('[data-elementor-type=\"wp-page\"]').children().last().before($('.other_services_container'));\n                var sections = $('[data-elementor-type=\"wp-page\"]').find('.net-15.dt-16');\n                $($('#form-templates').parents('.elementor-section')).before($('.other_services_container'));\n                for(var i = 0; i<sections.length; i++){\n                    if($(sections[i]).hasClass( 'net-15' ) && $(sections[i]).hasClass( 'dt-16' ) && $(sections[i]).hasClass( 'elementor-hidden-desktop' )==false){\n                        $(sections[i]).before($('.other_services_container'));\n                        if($(sections[i]).css('background-color')=='rgb(255, 255, 255)' || $(sections[i]).css('background-color')=='rgba(0, 0, 0, 0)'){\n                            $('.other_services_container').find('.elementor-section').css('background-color','#FBFBFD');\n                        }      \n                    }\n                }\n                \n            });\n        <\/script>","protected":false},"excerpt":{"rendered":"<p>Logistics software development services Tired of late deliveries and fragmented systems eating into your margins? Innowise\u2019s logistics software development services bring live tracking, AI-driven routing, and automated workflows into your supply chain, so you slash costs and hit every ETA. Start my solution 40+ logistics software development projects 60+ logistics developers years delivering logistics software [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":188933,"parent":15813,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-158736","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/pages\/158736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/comments?post=158736"}],"version-history":[{"count":0,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/pages\/158736\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/pages\/15813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/media\/188933"}],"wp:attachment":[{"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/media?parent=158736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}