{"id":137927,"date":"2023-11-07T11:32:42","date_gmt":"2023-11-07T08:32:42","guid":{"rendered":"https:\/\/innowise.com\/?page_id=137927"},"modified":"2026-05-22T11:56:08","modified_gmt":"2026-05-22T15:56:08","slug":"fitness-app-utveckling","status":"publish","type":"page","link":"https:\/\/innowise.com\/sv\/industries\/healthcare\/fitness-app-development\/","title":{"rendered":"Utvecklingsf\u00f6retag f\u00f6r fitnessappar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"137927\" class=\"elementor elementor-137927\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b601137 container-header back-animations e-con-full e-flex e-con e-parent\" data-id=\"b601137\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-676475f e-con-full e-flex e-con e-child\" data-id=\"676475f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59b9391 word-break elementor-widget elementor-widget-heading\" data-id=\"59b9391\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fitness app development company \n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b0d1671 e-con-full elementor-hidden-desktop e-flex e-con e-child\" data-id=\"b0d1671\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bcffe0a e-con-full e-flex e-con e-child\" data-id=\"bcffe0a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7531a0f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7531a0f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>With 18 years in IT, Innowise turns health and fitness app ideas into scalable products loved by users worldwide. Designed for both iOS and Android, our custom apps support training, wellness, and sports performance tracking at scale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f5bd32 elementor-align-center elementor-mobile-align-center elementor-widget-mobile__width-inherit elementor-tablet-align-left elementor-widget-tablet__width-initial ctaFirst elementor-widget elementor-widget-button\" data-id=\"5f5bd32\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\" id=\"main-block-link\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hire our developers<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a1cd751 firstSqr e-flex e-con-boxed e-con e-child\" data-id=\"a1cd751\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e7505c elementor-widget-tablet__width-inherit elementor-widget-mobile__width-inherit elementor-widget elementor-widget-html\" data-id=\"1e7505c\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"animated-wrapper\">\n    <div class=\"animated-text mobile\">\n       <div class=\"swiper-wrapper\">  \n        <div class=\"message swiper-slide\">\n            <p class=\"number\">60+<\/p>\n            <p class=\"description\">health and fitness apps delivered<\/p>\n        <\/div>\n        \n        <div class=\"message swiper-slide\">\n            <p class=\"number\">40+<\/p>\n            <p class=\"description\">health and fitness app developers<\/p>\n        <\/div>\n        \n        \n        <div class=\"message swiper-slide\">\n            <p class=\"number\">85%<\/p>\n            <p class=\"description\">senior & mid-level specialists<\/p>\n        <\/div>        \n      <\/div>    \n\n    <\/div>\n    <div class=\"clutch-widget-container\">\n        <img decoding=\"async\" class=\"clutch-image\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/06\/Clutch-Logo.svg\"\/ alt=\"\">\n\n        <a rel=\"nofollow\" href=\"https:\/\/clutch.co\/profile\/innowise?utm_source=widget&utm_medium=2&utm_campaign=widget&utm_content=logo&utm_term=innowise-group.com\" class=\"circle-button\" target=\"_blank\">\n            <svg width=\"45\" height=\"45\" viewBox=\"0 0 45 45\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect x=\"0.5\" y=\"0.828125\" width=\"44\" height=\"44\" rx=\"22\" fill=\"#C63031\"\/>\n<path d=\"M22.5 14.8281L30.5 22.8281L22.5 30.8281\" stroke=\"white\" stroke-width=\"2\"\/>\n<path d=\"M13.5 22.8282L30.5 22.8282\" stroke=\"white\" stroke-width=\"2\"\/>\n<\/svg>\n        <\/a>\n        \n\n\n    <\/div>\n<\/div>\n\n\n\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", function() {\n    \n  const sqrSwiper = new Swiper('.animated-text.mobile', {\n    slidesPerView: 1,\n   spaceBetween: 24, \n    allowTouchMove:false, \n     loop: true,\n  direction:\"vertical\",\n  autoHeight:true,\n     autoplay: {\n        delay: 4000,\n        disableOnInteraction: false,\n      },\n  });  \n  \n\n\n});\n\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c4f038 elementor-widget-tablet__width-inherit elementor-widget__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"7c4f038\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>With <span id=\"years-expirience\">19+<\/span> years in IT, Innowise turns health and fitness app ideas into scalable products loved by users worldwide. Designed for both iOS and Android, our custom apps support training, wellness, and sports performance tracking at scale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-754c362 elementor-hidden-tablet elementor-hidden-mobile elementor-widget__width-initial ctaFirst elementor-widget elementor-widget-button\" data-id=\"754c362\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hire our developers<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b820d76 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"b820d76\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-539b0f3 elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"539b0f3\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"animated-wrapper\">\n    <div class=\"animated-text pc\">\n       <div class=\"swiper-wrapper\">  \n        <div class=\"message swiper-slide\">\n            <p class=\"number\">60+<\/p>\n            <p class=\"description\">health and fitness apps delivered<\/p>\n        <\/div>\n        \n        <div class=\"message swiper-slide\">\n            <p class=\"number\">40+<\/p>\n            <p class=\"description\"> health and fitness app developers<\/p>\n        <\/div>\n        \n        \n        <div class=\"message swiper-slide\">\n            <p class=\"number\">85%<\/p>\n            <p class=\"description\">senior & mid-level specialists<\/p>\n        <\/div>        \n      <\/div>    \n\n    <\/div>\n    <div class=\"clutch-widget-container\">\n        <img decoding=\"async\" class=\"clutch-image\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/06\/Clutch-Logo.svg\"\/ alt=\"\">\n\n        <a rel=\"nofollow\" href=\"https:\/\/clutch.co\/profile\/innowise?utm_source=widget&utm_medium=2&utm_campaign=widget&utm_content=logo&utm_term=innowise-group.com\" class=\"circle-button\" target=\"_blank\">\n            <svg width=\"45\" height=\"45\" viewBox=\"0 0 45 45\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect x=\"0.5\" y=\"0.828125\" width=\"44\" height=\"44\" rx=\"22\" fill=\"#C63031\"\/>\n<path d=\"M22.5 14.8281L30.5 22.8281L22.5 30.8281\" stroke=\"white\" stroke-width=\"2\"\/>\n<path d=\"M13.5 22.8282L30.5 22.8282\" stroke=\"white\" stroke-width=\"2\"\/>\n<\/svg>\n        <\/a>\n        \n\n\n    <\/div>\n<\/div>\n\n\n<script>\n\n\ndocument.addEventListener(\"DOMContentLoaded\", function() {\n    \n\n\n    \n  const sqrSwiper = new Swiper('.animated-text.pc', {\n    slidesPerView: 1,\n   spaceBetween: 24, \n    allowTouchMove:false, \n     loop: true,\n  direction:\"vertical\",\n     autoplay: {\n        delay: 4000,\n        disableOnInteraction: false,\n      },\n  });      \n  \n\n});\n\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e13412 e-flex e-con-boxed e-con e-parent\" data-id=\"9e13412\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3664dde elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"3664dde\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Health and fitness app development services \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abc7180 switcher-section elementor-widget elementor-widget-html\" data-id=\"abc7180\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"domains-container-new\">\r\n  <ul class=\"domains__list-new\">\r\n     <li class=\"active\">Custom fitness app development<\/li>\r\n     <li>Fitness app UX\/UI design<\/li>\r\n     <li>Wearable device integration<\/li>\r\n     <li>Fitness device companion apps<\/li>\r\n     <li>Performance optimization<\/li>\r\n     <li>App modernization & upgrades<\/li>\r\n  <\/ul>\r\n\r\n  <div class=\"domains__descriptions-new\">\r\n    <div class=\"swiper-wrapper\">\r\n      <div class=\"swiper-slide swiper-slide-active\">\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Custom fitness app development<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">From ultra-niche apps to all-in-one platforms, we create with you from the ground up. Develop feature-rich experiences for users supported by faultless architecture.<\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Custom-fitness-app-development.png\" alt=\"Custom Fitness App Development\">\r\n        <\/div>\r\n      <\/div>\r\n      <div class=\"swiper-slide\">\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Fitness app UX\/UI design<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">We design with the end user in mind \u2014 intuitive, habit-forming interfaces that skyrocket retention and delight users with every tap, swipe, and session.<\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Fitness-app-UXUI-design.png\" alt=\"Fitness App UX\/UI Design\">\r\n        <\/div>\r\n      <\/div>\r\n      <div class=\"swiper-slide\">\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Wearable device integration<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">With IoT expertise, we offer built-in support for wearables, like smart watches or heart rate monitors. Allowing real-time activity tracking and seamless data syncs.<\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Wearable-device-integration.png\" alt=\"Wearable Device Integration\">\r\n        <\/div>\r\n      <\/div>\r\n      <div class=\"swiper-slide\">\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Fitness device companion apps<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">From smart treadmills to interactive rowing machines, we create reliable, easy-to-pair companion apps that unlock the full potential of your fitness devices.<\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Fitness-device-companion-apps.png\" alt=\"Fitness Device Companion Apps\">\r\n        <\/div>\r\n      <\/div>\r\n      <div class=\"swiper-slide\">\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>Performance optimization<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">Slow load times or frequent crashes? We fix bottlenecks and strengthen back-end performance so your fitness app handles traffic spikes without skipping a beat.<\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Performance-optimization.png\" alt=\"Performance Optimization\">\r\n        <\/div>\r\n      <\/div>\r\n      <div class=\"swiper-slide\">\r\n        <div>\r\n          <div class=\"slider-title-new\"><h3>App modernization & upgrades<\/h3><\/div>\r\n          <p class=\"slider-desc-new\">Legacy code, clunky UX, dated features, and old security protocols \u2014 we replace everything that holds you back, helping you get up to speed and attract new users.<\/p>\r\n        <\/div>\r\n        <div class=\"slider-image-block-new\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/App-modernization-upgrades.png\" alt=\"App Modernization & Upgrades\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\r\n\r\n<div class=\"mobile-domains-new\">\r\n  <div class=\"mobile-domains-navitem-new active\" data-mobile-domain=\"domain-1\">\r\n    <span>Custom fitness app development<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">From ultra-niche apps to all-in-one platforms, we create with you from the ground up. Develop feature-rich experiences for users supported by faultless architecture.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Custom-fitness-app-development.png\" alt=\"Custom Fitness App Development\">\r\n    <\/p>\r\n  <\/div>\r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-2\">\r\n    <span>Fitness app UX\/UI design<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">We design with the end user in mind \u2014 intuitive, habit-forming interfaces that skyrocket retention and delight users with every tap, swipe, and session.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Fitness-app-UXUI-design.png\" alt=\"Fitness App UX\/UI Design\">\r\n    <\/p>\r\n  <\/div>\r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-3\">\r\n    <span>Wearable device integration<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">With IoT expertise, we offer built-in support for wearables, like smart watches or heart rate monitors. Allowing real-time activity tracking and seamless data syncs.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Wearable-device-integration.png\" alt=\"Wearable Device Integration\">\r\n    <\/p>\r\n  <\/div>\r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-4\">\r\n    <span>Fitness device companion apps<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">From smart treadmills to interactive rowing machines, we create reliable, easy-to-pair companion apps that unlock the full potential of your fitness devices.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Fitness-device-companion-apps.png\" alt=\"Fitness Device Companion Apps\">\r\n    <\/p>\r\n  <\/div>\r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-5\">\r\n    <span>Performance optimization<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">Slow load times or frequent crashes? We fix bottlenecks and strengthen back-end performance so your fitness app handles traffic spikes without skipping a beat.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Performance-optimization.png\" alt=\"Performance Optimization\">\r\n    <\/p>\r\n  <\/div>\r\n  <div class=\"mobile-domains-navitem-new\" data-mobile-domain=\"domain-6\">\r\n    <span>App modernization & upgrades<\/span>\r\n    <p class=\"slider-desc-new mobile-domain-list-new\">Legacy code, clunky UX, dated features, and old security protocols \u2014 we replace everything that holds you back, helping you get up to speed and attract new users.\r\n      <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/App-modernization-upgrades.png\" alt=\"App Modernization & Upgrades\">\r\n    <\/p>\r\n  <\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<script>\r\n\r\ndocument.addEventListener('DOMContentLoaded', () => {\r\n    const mobileNavItems = document.querySelectorAll('.mobile-domains-navitem-new');\r\n\r\n    mobileNavItems.forEach(item => {\r\n        item.addEventListener('click', () => {\r\n            const isActive = item.classList.contains('active');\r\n\r\n            \/\/ Collapse all items\r\n            mobileNavItems.forEach(nav => {\r\n                nav.classList.remove('active');\r\n                const ul = nav.querySelector('.mobile-domain-list');\r\n                if (ul) ul.style.maxHeight = '0';\r\n            });\r\n\r\n            \/\/ Expand clicked item only if it was not active\r\n            if (!isActive) {\r\n                item.classList.add('active');\r\n                const ul = item.querySelector('.mobile-domain-list');\r\n                if (ul) ul.style.maxHeight = ul.scrollHeight + 'px';\r\n            }\r\n        });\r\n    });\r\n    \r\n    const firstNavItem = mobileNavItems.item(0);\r\n    \r\n    if (firstNavItem && !firstNavItem.classList.contains('active')) {\r\n        firstNavItem.click();\r\n    }\r\n});\r\n\r\n<\/script>\r\n\r\n\r\n<script>\r\n\r\ndocument.addEventListener('DOMContentLoaded', () => {\r\n    \r\n  const domainsSwiper = new Swiper('.domains__descriptions-new', {\r\n    slidesPerView: 1,\r\n   spaceBetween: 24, \r\n       effect:'fade',\r\n    allowTouchMove:false,   \r\n       \r\n  });  \r\n    \r\n\r\nconst domainsListItems = document.querySelectorAll(\r\n  '.domains__list-new li'\r\n);\r\n\r\nconst rightPart = document.querySelector(\r\n  '.domains__descriptions-new'\r\n);\r\n\r\nconst leftPart = document.querySelector(\r\n  '.domains__list-new'\r\n);\r\n\r\n\r\nconst rightPartHeight = rightPart.getBoundingClientRect().height\r\n\r\nif(rightPartHeight > leftPart.getBoundingClientRect().height){\r\n    leftPart.style.minHeight = `${rightPartHeight}px`;\r\n}\r\n\r\n\r\n\r\n\r\n\r\ndomainsListItems.forEach((domainsListItem, domainsListItemIndex, arr) => {\r\n    \r\n  domainsListItem.addEventListener('click', () => {\r\n    arr.forEach((item,i) => {\r\n      if (item === domainsListItem) {\r\n        item.classList.add('active');\r\n        domainsSwiper.slideTo(i);\r\n      } else {\r\n        item.classList.remove('active');\r\n      }\r\n    });\r\n    \r\n  });\r\n});\r\n\r\n\r\n\r\n\r\n\r\n});\r\n\r\n<\/script>\r\n\r\n\r\n\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-88aa8c3 e-flex e-con-boxed e-con e-parent\" data-id=\"88aa8c3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9278c84 elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"9278c84\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We develop all kinds of fitness apps<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35ac1e5 elementor-widget elementor-widget-html\" data-id=\"35ac1e5\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"python-container\">\n    \n    <div class=\"python-item\">\n        <span class=\"python-item-title\">Workout apps<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/376.png\" \/ alt=\"\">\n    <\/div>\n\n   <div class=\"python-item\">\n        <span class=\"python-item-title\">Wellness apps<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/346.svg\" \/ alt=\"\">\n    <\/div>\n    \n    <div class=\"python-item\">\n        <span class=\"python-item-title\">Personal trainer apps<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/379.png\" \/ alt=\"\">\n    <\/div>\n    \n    <div class=\"python-item\">\n        <span class=\"python-item-title\">Diet & nutrition apps\n<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/377.svg\" \/ alt=\"\">\n    <\/div>\n    \n    <div class=\"python-item\">\n        <span class=\"python-item-title\">Activity tracker apps<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/02\/109.svg\" \/ alt=\"\">\n    <\/div>\n    \n    <div class=\"python-item\">\n        <span class=\"python-item-title\">Sleep cycle apps<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/05\/354.svg\" \/ alt=\"\">\n    <\/div>\n    \n      <div class=\"python-item close\">\n        <span class=\"python-item-title\">Meditation & yoga apps<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/378.svg\" \/ alt=\"\">\n    <\/div>\n\n    <div class=\"python-item close\">\n        <span class=\"python-item-title\">Social media fitness apps<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/380.png\" \/ alt=\"\">\n    <\/div>\n    \n    <a class=\"python-item close\" href=\"https:\/\/innowise.com\/blog\/mental-health-app-development\/\" >\n    <div>\n        <span class=\"python-item-title\">Mood tracking apps<\/span>\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/05\/350.svg\" \/ alt=\"\">\n    <\/div>\n    <\/a>\n  \n<\/div>\n\n<div class=\"show-more-python close\">\n  <span> Show all<\/span>\n  <span> Show less<\/span>\n<\/div>\n\n<style>\n    .python-item {\n        text-decoration: none !important;\n    }\n<\/style>\n   \n \n<script>\n  document.addEventListener(\"DOMContentLoaded\", () => {\n\n    const showMorePython = document.querySelector(\".show-more-python\");\n    const pythonItems = document.querySelectorAll(\".python-container .python-item\");\n\n    showMorePython.addEventListener(\"click\", () => {\n\n\n\n\n      pythonItems.forEach((item, index) => {\n        if (index >= 6) {\n          if (item.classList.contains('close')) {\n\n            showMorePython.classList.remove('close');\n            item.classList.remove('close')\n          } else {\n\n            showMorePython.classList.add('close');\n            item.classList.add('close')\n          }\n\n        }\n      });\n\n\n    });\n\n  });\n\n<\/script>   \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66854ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66854ae\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ceb3331\" data-id=\"ceb3331\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6beb8d elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"c6beb8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our health and fitness apps development portfolio<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ae49cc elementor-widget elementor-widget-shortcode\" data-id=\"6ae49cc\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n        <div class=\"slider-overflow view-\">\n            <div class=\"swiper-related view-\">\n                <div class=\"swiper-wrapper\">\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/breast-cancer-detection-with-federated-learning\/\" aria-label=\"block_198695\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/07\/collaborative-mammography-segmentation.png\" alt=\"Privacy-preserving breast cancer detection with federated learning\">\n                    <div class=\"cases-post__thumbnail_opencase_img\">\n                        <div>\n                            <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/07\/Log\u043es-desktop-2.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                \n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/breast-cancer-detection-with-federated-learning\/\" aria-label=\"Privacy-preserving breast cancer detection with federated learning\" >Privacy-preserving breast cancer detection with federated learning<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/healthcare\/\">Healthcare<\/a><a href=\"\/sv\/cases\/computer-vision\/\">Computer vision<\/a><a href=\"\/sv\/cases\/ai\/\">AI<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/breast-cancer-detection-with-federated-learning\/\" aria-label=\"Read more about Privacy-preserving breast cancer detection with federated learning\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/ios-and-vr-meditation-app-development\/\" aria-label=\"block_194217\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/03\/iOS-and-VR-meditation-app-suite-for-Grozio-Planeta-UAB-2.png\" alt=\"iOS and VR meditation app suite for Gro\u017eio Planeta UAB\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/ios-and-vr-meditation-app-development\/\" aria-label=\"iOS and VR meditation app suite for Gro\u017eio Planeta UAB\" >iOS and VR meditation app suite for Gro\u017eio Planeta UAB<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/healthcare\/\">Healthcare<\/a><a href=\"\/sv\/cases\/django\/\">Django<\/a><a href=\"\/sv\/cases\/aws\/\">AWS<\/a><a href=\"\/sv\/cases\/mobile-development\/\">Mobile development<\/a><a href=\"\/sv\/cases\/php\/\">PHP<\/a><a href=\"\/sv\/cases\/python\/\">Python<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/ios-and-vr-meditation-app-development\/\" aria-label=\"Read more about iOS and VR meditation app suite for Gro\u017eio Planeta UAB\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/custom-fhir-integration-gateway\/\" aria-label=\"block_193309\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/03\/image-teaser-fim.jpg\" alt=\"Designing a data integration gateway for FIM Medical\">\n                    <div class=\"cases-post__thumbnail_opencase_img\">\n                        <div>\n                            <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/03\/Log\u043es-desktop-1.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                \n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/custom-fhir-integration-gateway\/\" aria-label=\"Designing a data integration gateway for FIM Medical\" >Designing a data integration gateway for FIM Medical<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/healthcare\/\">Healthcare<\/a><a href=\"\/sv\/cases\/c\/\">C#<\/a><a href=\"\/sv\/cases\/net\/\">.NET<\/a><a href=\"\/sv\/cases\/integrering\/\">Integration<\/a><a href=\"\/sv\/cases\/staff-augmentation\/\">Staff augmentation<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/custom-fhir-integration-gateway\/\" aria-label=\"Read more about Designing a data integration gateway for FIM Medical\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/rfid-tag-for-telea-medical\/\" aria-label=\"block_188568\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/10\/Hero-image-1.jpg\" alt=\"RFID tag data decoding module for Telea Medical\">\n                    <div class=\"cases-post__thumbnail_opencase_img\">\n                        <div>\n                            <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/10\/proptelea.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                \n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/rfid-tag-for-telea-medical\/\" aria-label=\"RFID tag data decoding module for Telea Medical\" >RFID tag data decoding module for Telea Medical<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/healthcare\/\">Healthcare<\/a><a href=\"\/sv\/cases\/integrering\/\">Integration<\/a><a href=\"\/sv\/cases\/iot\/\">IoT<\/a><a href=\"\/sv\/cases\/staff-augmentation\/\">Staff augmentation<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/rfid-tag-for-telea-medical\/\" aria-label=\"Read more about RFID tag data decoding module for Telea Medical\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/gym-membership-management-app\/\" aria-label=\"block_183165\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/05\/Small-cover-Gym-membership-app-support-and-improvement-for-enhanced-member-tracking.png\" alt=\"Gym membership app support &#038; improvement\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/gym-membership-management-app\/\" aria-label=\"Gym membership app support & improvement\" >Gym membership app support & improvement<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/healthcare\/\">Healthcare<\/a><a href=\"\/sv\/cases\/flutter\/\">Flutter<\/a><a href=\"\/sv\/cases\/mobile\/\">Mobile<\/a><a href=\"\/sv\/cases\/mobile-development\/\">Mobile development<\/a><a href=\"\/sv\/cases\/sport-lifestyle\/\">Sport &amp; lifestyle<\/a><a href=\"\/sv\/cases\/staff-augmentation\/\">Staff augmentation<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/gym-membership-management-app\/\" aria-label=\"Read more about Gym membership app support & improvement\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/radiation-exposure-monitoring-app-upgrade\/\" aria-label=\"block_179795\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/03\/Small-Cover-Upgrade-of-a-radiation-exposure-monitoring-app-Anya-Kh.-Anna-Kr.png\" alt=\"Upgrade of a radiation exposure monitoring app\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/radiation-exposure-monitoring-app-upgrade\/\" aria-label=\"Upgrade of a radiation exposure monitoring app\" >Upgrade of a radiation exposure monitoring app<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/healthcare\/\">Healthcare<\/a><a href=\"\/sv\/cases\/audit\/\">Audit<\/a><a href=\"\/sv\/cases\/ecology\/\">Ecology<\/a><a href=\"\/sv\/cases\/energy\/\">Energy<\/a><a href=\"\/sv\/cases\/angular\/\">Angular<\/a><a href=\"\/sv\/cases\/node-js\/\">Node.js<\/a><a href=\"\/sv\/cases\/software-enhancement\/\">Software enhancement<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/radiation-exposure-monitoring-app-upgrade\/\" aria-label=\"Read more about Upgrade of a radiation exposure monitoring app\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/monolithic-to-microservices-migration\/\" aria-label=\"block_179235\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/02\/Small-Cover-Monolithic-to-microservices-migration_-25-faster-response.png\" alt=\"Monolithic to microservices migration\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/monolithic-to-microservices-migration\/\" aria-label=\"Monolithic to microservices migration\" >Monolithic to microservices migration<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/healthcare\/\">Healthcare<\/a><a href=\"\/sv\/cases\/angular\/\">Angular<\/a><a href=\"\/sv\/cases\/java\/\">Java<\/a><a href=\"\/sv\/cases\/microservices\/\">Microservices<\/a><a href=\"\/sv\/cases\/typescript\/\">TypeScript<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/monolithic-to-microservices-migration\/\" aria-label=\"Read more about Monolithic to microservices migration\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n        <div class=\"swiper-slide\">\n            <div class=\"swiper-into-e1\">\n                <div class=\"swiper-slide__inner-container\">\n                    <div class=\"block-div-img-rel\">\n                        <a href=\"https:\/\/innowise.com\/sv\/case\/ai-skin-scanner-app\/\" aria-label=\"block_176624\">\n                            <img decoding=\"async\" class=\"slide__img-rel\" \n                             src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/01\/small-cover-1.jpg\" alt=\"AI dermatologist skin scanner app\">\n                        <\/a>\n                    <\/div>\n                    <div class=\"border-slide-rel\">\n                        <div class=\"swip-title-rel-qe mb-10\" style=\"\">\n                            <a href=\"https:\/\/innowise.com\/sv\/case\/ai-skin-scanner-app\/\" aria-label=\"AI dermatologist skin scanner app\" >AI dermatologist skin scanner app<\/a>\n                        <\/div>\n                        <div class=\"swip-array-rel\">\n                            <a href=\"\/sv\/cases\/healthcare\/\">Healthcare<\/a><a href=\"\/sv\/cases\/android\/\">Android<\/a><a href=\"\/sv\/cases\/angular\/\">Angular<\/a><a href=\"\/sv\/cases\/aws\/\">AWS<\/a><a href=\"\/sv\/cases\/flutter\/\">Flutter<\/a><a href=\"\/sv\/cases\/ai\/\">AI<\/a><a href=\"\/sv\/cases\/ios\/\">iOS<\/a>\n                        <\/div>\n                        <div class=\"slide__button-wrapper_mob\">\n                            <span class=\"slide__button-text_mob\">Read more<\/span>\n                            <img decoding=\"async\" class=\"slide__button-img_mob\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2021\/12\/arrow-more.svg\" alt=\"\">\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"slide__button-wrapper\">\n                <a href=\"https:\/\/innowise.com\/sv\/case\/ai-skin-scanner-app\/\" aria-label=\"Read more about AI dermatologist skin scanner app\">\n                    <div class=\"arrow-btn3-rel\">\n                        <svg class=\"arrow-btn__svg\"\n                             width=\"110\"\n                             height=\"18\"\n                             viewBox=\"0 0 110 18\"\n                             fill=\"none\"\n                             xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M9 1L17 8.99999L9 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M0 9.00018L17 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M99 1L107 8.99999L99 17\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                            <path d=\"M90 9.00018L107 9.00018\"\n                                  stroke=\"#C63031\"\n                                  stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/div>\n                <\/a>\n            <\/div>\n        <\/div>\n                <\/div>\n                \n                <div class=\"swiper-related__navigation\" style=\"\">\n                    <button class=\"swiper-related__navigation-btn\" style=\"\">\n                        <svg width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <g>\n                                <path d=\"M12 4L4 12L12 20\" stroke=\"#2E2E2E\" stroke-width=\"2\"\/>\n                                <path d=\"M21 12.0002L4 12.0002\" stroke=\"#2E2E2E\" stroke-width=\"2\"\/>\n                            <\/g>\n                        <\/svg>\n                    <\/button>\n                \n                    <button class=\"swiper-related__navigation-btn\" style=\"\">\n                        <svg width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M13 4L21 12L13 20\" stroke=\"#2E2E2E\" stroke-width=\"2\"\/>\n                            <path d=\"M4 12.0002L21 12.0002\" stroke=\"#2E2E2E\" stroke-width=\"2\"\/>\n                        <\/svg>\n                    <\/button>\n                <\/div>\n            <\/div>\n        <\/div>\n            <div class=\"cases-swiper-pagination case-slider-pagination\"><\/div>\n        <script src=\"\/wp-content\/themes\/hello-elementor\/assets\/js\/slb-case.js\"><\/script>  \n        <link rel=\"stylesheet\" href=\"\/wp-content\/themes\/hello-elementor\/assets\/css\/case-slider.css\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8466ec5 e-flex e-con-boxed e-con e-parent\" data-id=\"8466ec5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2866a5 elementor-widget elementor-widget-html\" data-id=\"c2866a5\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div style=\"display:none !important; margin-top: 0; padding: 0;\" class=\"m-technological-all\">\n        <span><a style=\"all: unset; cursor: pointer;\" href=\"https:\/\/innowise.com\/cases\/\">All case studies<\/a><\/span>\n    <\/div>\n   \n    \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-9e5edbc e-flex e-con-boxed e-con e-parent\" data-id=\"9e5edbc\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f6523ba e-con-full e-flex e-con e-child\" data-id=\"f6523ba\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7932782 elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"7932782\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ready to launch a fitness software development project?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e84c56c elementor-align-justify elementor-widget__width-initial elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"e84c56c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Talk to our experts<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1da413 radGreedWrapper link-underline e-flex e-con-boxed e-con e-parent\" data-id=\"d1da413\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-246b58a elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"246b58a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Essential features we develop for fitness apps\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b8ce089 e-grid e-con-full e-con e-child\" data-id=\"b8ce089\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-efed8ee e-flex e-con-boxed e-con e-child\" data-id=\"efed8ee\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20c4d2e elementor-widget elementor-widget-text-editor\" data-id=\"20c4d2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Personal profiles<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ae36b2 elementor-widget elementor-widget-text-editor\" data-id=\"5ae36b2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Users can track their workout progress and health stats, see their GPS running maps, and set wellness goals in one place. All that supports fitness personalization and long-term motivation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4fe7b66 e-flex e-con-boxed e-con e-child\" data-id=\"4fe7b66\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a1c4376 elementor-widget elementor-widget-text-editor\" data-id=\"a1c4376\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Smart exercise library <\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd5b6c2 elementor-widget elementor-widget-text-editor\" data-id=\"fd5b6c2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We design workout libraries with guided programs, filters by fitness level, and playlists that sync with users\u2019 favorite music streaming services. Thanks to that, your audience gets content that helps them achieve their goals effortlessly.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a016edf e-flex e-con-boxed e-con e-child\" data-id=\"a016edf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61bce47 elementor-widget elementor-widget-text-editor\" data-id=\"61bce47\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Nutrition guidance <\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6288f54 elementor-widget elementor-widget-text-editor\" data-id=\"6288f54\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The nutrition module supports customized diet plans, calorie tracking, and energy value insights tailored to individual workout programs. With these features, your fitness app becomes a go-to wellness hub, not just a workout log.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39f1f67 e-flex e-con-boxed e-con e-child\" data-id=\"39f1f67\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39becac elementor-widget elementor-widget-text-editor\" data-id=\"39becac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Gamification &amp; engagement <\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9844413 elementor-widget elementor-widget-text-editor\" data-id=\"9844413\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>To motivate users in their fitness journey, Innowise\u2019s team creates features like challenges, workout streaks, social sharing, and in-app competitions with friends. Plus, we add push notifications that nudge users to stay on track.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f9b415 e-flex e-con-boxed e-con e-child\" data-id=\"0f9b415\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd61245 elementor-widget elementor-widget-text-editor\" data-id=\"bd61245\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Integration with wearables <\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7686bb8 elementor-widget elementor-widget-text-editor\" data-id=\"7686bb8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Via ready-made APIs or custom integrations, we <a href=\"https:\/\/innowise.com\/services\/mobile-application-development\/wearable\/\" rel=\"noopener\">sync your fitness app with wearables<\/a>, like Apple Watch, Fitbit, Garmin, and others. It lets you pull in real-time health metrics, make progress tracking more fact-based, and gain a competitive edge.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12dd49b e-con-full e-flex e-con e-child\" data-id=\"12dd49b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d92d8c elementor-widget elementor-widget-text-editor\" data-id=\"3d92d8c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"red-dot\">Payment module <\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21d9b88 elementor-widget elementor-widget-text-editor\" data-id=\"21d9b88\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Whether you need to implement subscriptions, one-time purchases, or tiered access models, Innowise can make this happen. We embed secure payments via popular gateways, like Google Pay, Apple Pay, Samsung Pay, Stripe, PayPal, and others. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-556483d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"556483d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0932d38\" data-id=\"0932d38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-084d86c elementor-widget elementor-widget-shortcode\" data-id=\"084d86c\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">[clients_logos]<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1686501 e-flex e-con-boxed e-con e-parent\" data-id=\"1686501\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e42c1a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6e42c1a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Industries we serve<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b91ae2 elementor-widget elementor-widget-html\" data-id=\"6b91ae2\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"x-industries__list\">\r\n  <div class=\"x-industries__swiper\">\r\n    <ul class=\"x-industries__list_container swiper-wrapper\">\r\n      <li class=\"swiper-slide active\">Video analytics<\/li>\r\n      <li class=\"swiper-slide\">Chatbots<\/li>\r\n      <li class=\"swiper-slide\">Workout plans<\/li>\r\n      <li class=\"swiper-slide\">Live workouts<\/li>\r\n      <li class=\"swiper-slide\">AR<\/li>\r\n    <\/ul>\r\n  <\/div>\r\n\r\n  <div class=\"x-industries__navigation\">\r\n    <button class=\"x-industries__navigation-btn\">\r\n      <svg width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n        <g>\r\n          <path d=\"M12 4L4 12L12 20\" stroke=\"#2E2E2E\" stroke-width=\"2\" \/>\r\n          <path d=\"M21 12.0002L4 12.0002\" stroke=\"#2E2E2E\" stroke-width=\"2\" \/>\r\n        <\/g>\r\n      <\/svg>\r\n    <\/button>\r\n\r\n    <button class=\"x-industries__navigation-btn\">\r\n      <svg width=\"25\" height=\"24\" viewBox=\"0 0 25 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\r\n        <path d=\"M13 4L21 12L13 20\" stroke=\"#2E2E2E\" stroke-width=\"2\" \/>\r\n        <path d=\"M4 12.0002L21 12.0002\" stroke=\"#2E2E2E\" stroke-width=\"2\" \/>\r\n      <\/svg>\r\n    <\/button>\r\n  <\/div>\r\n<\/div>\r\n\r\n  \r\n  \r\n<script >\r\n\r\ndocument.addEventListener(\"DOMContentLoaded\", function() {\r\n\r\n\r\n  const xindustriesListItems = document.querySelectorAll('.x-industries__list_container li');\r\n  \r\n  const industriesSlider1 = new Swiper('.x-industries__swiper', {\r\n    slidesPerView: 'auto',\r\n    spaceBetween: 24,  \r\n\r\n      watchSlidesProgress: true,\r\n    grabCursor: true,\r\n    \r\n    \r\n          \r\n  breakpoints: {\r\n   280: {\r\n    spaceBetween: 20, \r\n    },\r\n\r\n\r\n     820: {\r\n    spaceBetween: 24, \r\n    },\r\n  } \r\n    \r\n\r\n  });\r\n  \r\n\r\n  \r\n  const industriesSlider2 = new Swiper('.industries__swiper', {\r\n    slidesPerView: 1,\r\n   spaceBetween: 24, \r\n       effect:'fade',\r\n    grabCursor: true,\r\n      thumbs: {\r\n        swiper: industriesSlider1 ,\r\n      },\r\n      navigation: {\r\n        nextEl: \".x-industries__navigation button:nth-child(2)\",\r\n        prevEl: \".x-industries__navigation button:nth-child(1)\",\r\n      },\r\n  });  \r\n    \r\n  \r\n  \r\n  \r\nindustriesSlider2.on('slideChange', function (data) {\r\n\r\nconst activeIndex = data.activeIndex;\r\n\r\n industriesSlider1.slideTo(activeIndex);\r\n \r\n    \r\nxindustriesListItems.forEach((elem,i)=>{\r\n         if (activeIndex === i) {\r\n          elem.classList.add('active');\r\n        } else {\r\n          elem.classList.remove('active');\r\n        }   \r\n}) \r\n\r\n});  \r\n  \r\n});  \r\n  \r\n<\/script>\r\n\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d77587a elementor-widget elementor-widget-html\" data-id=\"d77587a\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"x-industries__descriptions industries__swiper\">\r\n  <div class=\"swiper-wrapper\">\r\n\r\n    <!-- AI Video Analytics -->\r\n    <div class=\"x-industries__descriptions-item swiper-slide swiper-slide-active\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>AI video analytics<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          The fitness app records exercises and, thanks to real-time movement analysis, tracks form, range of motion, and exercise accuracy, giving users instant feedback and safer workouts.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Detects posture and rep errors<\/li>\r\n          <li>Improves training quality<\/li>\r\n          <li>No external input required<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/AI-video-analytics.png\" alt=\"AI video analytics\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <!-- Intelligent Virtual Coaches -->\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>Intelligent virtual coaches<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          Smart assistants offer 24\/7 guidance throughout the fitness journey, answer workout questions, motivate users, and suggest timely corrections based on user behavior.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Personalized workout advice<\/li>\r\n          <li>Real-time motivation and tips to avoid injuries<\/li>\r\n          <li>Behavioral insights<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Intelligent-virtual-coaches.png\" alt=\"Intelligent virtual coaches\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <!-- Adaptive Workout Plans -->\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>Adaptive workout plans<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          Thanks to AI personalization tools, workout routines adjust automatically based on the user\u2019s performance and progress, keeping them challenged but not overworked.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Adapts to personal fitness goals<\/li>\r\n          <li>Prevents user\u2019s burnout<\/li>\r\n          <li>Supports long-term results<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Adaptive-workout-plans.png\" alt=\"Adaptive workout plans\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <!-- Live Online Training -->\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>Live online training<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          Video chat connects users with real coaches who can monitor performance in real time, give immediate workout feedback, fix posture, and motivate in real time.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Real-time, human support<\/li>\r\n          <li>Interactive experience<\/li>\r\n          <li>Boosts user accountability for their results<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Live-online-training.png\" alt=\"Live online training\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n    <!-- AR Training Features -->\r\n    <div class=\"x-industries__descriptions-item swiper-slide\">\r\n      <div class=\"x-slider-info-block\">\r\n        <div class=\"x-slider-title\">\r\n          <h3>AR training features<\/h3>\r\n        <\/div>\r\n        <p class=\"x-slider-desc\">\r\n          With AR workout overlays in health and fitness apps, users see guided exercises mapped onto their space to make at-home training feel truly immersive and precise.\r\n        <\/p>\r\n        <ul class=\"x-slider-list\">\r\n          <li>Visual step-by-step guidance<\/li>\r\n          <li>Adds wow-factor to your fitness app<\/li>\r\n          <li>Reduces injury risk<\/li>\r\n        <\/ul>\r\n      <\/div>\r\n      <div class=\"x-slider-image-block\">\r\n        <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/AR-training-features.png\" alt=\"AR training features\" \/>\r\n      <\/div>\r\n    <\/div>\r\n\r\n  <\/div>\r\n<\/div>\r\n\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-763b67b e-flex e-con-boxed e-con e-parent\" data-id=\"763b67b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22b0998 elementor-widget elementor-widget-shortcode\" data-id=\"22b0998\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n    <div class=\"feedback-expert\">\n        <div class=\"feedback-expert-wrap\">\n            <div class=\"feedback-expert-img\">\n                <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2026\/05\/PersonAnastasiya-Dziemieszkiewicz.png\" alt=\"Anastasiya Dziemieszkiewicz\">\n            <\/div>\n            <div class=\"feedback-expert-content\">\n                <div class=\"feedback-expert-content-top\">\n                    With a background in healthcare, our fitness app development services are rooted in the actual value for end users. We at Innowise won\u2019t push you dozens of features that no one needs. Instead, my team and I will carefully craft a cohesive feature set that motivates users to change their lifestyle and put more effort into their fitness, keeping your company\u2019s profits high.                 <\/div>\n                <div class=\"feedback-expert-content-bottom\">\n                    <a href=\"https:\/\/innowise.com\/sv\/?page_id=154868\" class=\"feedback-expert-content-name\">\n                        Anastasiya Dziemieszkiewicz                    <\/a>\n                    <div class=\"feedback-expert-content-post\">\n                        Head of Healthcare Business Practice                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <style>\n        .feedback-expert{\n            background:url(\/wp-content\/themes\/hello-elementor\/assets\/images\/expert-back.png);\n            background-size:cover;\n        }\n        .feedback-expert-wrap{\n            margin:0 auto;\n            width:100%;\n            padding-left:16px;\n            padding-right:16px;\n            max-width:1280px;\n            display:flex;\n            gap:40px;\n            align-items:center;\n        }\n        .feedback-expert-img{\n            display:flex;\n            overflow:hidden;\n            width:400px;\n            min-width:400px;\n        }\n        .feedback-expert-img img{\n            display:block;\n            width:100%;\n        }\n        .feedback-expert-content{\n            display:flex;\n            flex-direction:column;\n            gap:30px;\n            max-width:800px;\n        }\n        .feedback-expert-content-top{\n            font-family: Karla;\n            font-weight: 400;\n            font-style: Regular;\n            font-size: 22px;\n            line-height: 28px;\n            letter-spacing: 0%;\n\n        }   \n        .feedback-expert-content-top a{\n        \ttext-decoration:underline;\n        }\n        .feedback-expert-content-bottom{\n\n        }\n        .feedback-expert-content-name{\n            font-family: Karla;\n            font-weight: 700;\n            font-style: Bold;\n            font-size: 24px;\n            line-height: 150%;\n            letter-spacing: 0%;\n            margin-bottom:3px;\n            color:rgba(198, 48, 49, 1);\n            border-bottom:1px solid transparent;\n            transition:0.5s;\n            display:block;\n            max-height: 36px;\n            width: fit-content;\n        }\n        .feedback-expert-content-name:hover{\n            border-bottom: 1px solid rgba(198, 48, 49, 1);\n        }\n        .feedback-expert-content-post{\n            font-family: Karla;\n            font-weight: 400;\n            font-style: Regular;\n            font-size: 18px;\n            line-height: 150%;\n            letter-spacing: 0%;\n            color:rgba(88, 88, 88, 1);\n        }\n        \n        @media(max-width:1024px){\n            .feedback-expert-wrap{\n                gap:0;\n            }\n            .feedback-expert-content{\n                padding-top:40px;\n                padding-bottom:40px;\n            }\n        }\n        @media(max-width:780px){\n            .feedback-expert{\n                background:url(\/wp-content\/themes\/hello-elementor\/assets\/images\/expert-back-m.png);\n            }\n            .feedback-expert-wrap{\n                gap:0px;\n                flex-direction:column;\n            }\n            .feedback-expert-img{\n                width:100%;\n                border-bottom: 1px solid rgba(196, 196, 196, 1);\n            }\n            .feedback-expert-img img{\n                margin:0 auto;\n                width:400px;\n            }\n            .feedback-expert-content{\n                gap:30px;\n            }\n        }\n        @media(max-width:768px){\n            .feedback-expert-img img{\n                width:266px;\n            }\n            .feedback-expert-content{\n                padding-top:30px;\n                padding-bottom:40px;\n                gap:20px;\n            }\n            .feedback-expert-content-top{\n                font-size: 16px;\n            }\n            .feedback-expert-content-name{\n                font-size:20px;\n            }\n            .feedback-expert-content-post{\n                font-size:14px;\n            }\n        }\n    <\/style>\n\n    <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-950fc54 e-flex e-con-boxed e-con e-parent\" data-id=\"950fc54\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca6f515 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"ca6f515\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our fitness software development process<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eb9226 roadmap-grid-2 elementor-widget elementor-widget-html\" data-id=\"6eb9226\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"new-steps-container\">\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">\n                Discovery\n            <\/span>\n            <!--<span class=\"new-step-item-duration\">1-2 hours<\/span>-->\n            <p class=\"new-step-item-text\">We start by diving deep into your fitness app vision, collecting requirements, identifying key features, and laying the groundwork for a solid product.<\/p>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">\n                Planning\n            <\/span>\n            <p class=\"new-step-item-text\">With a clear fitness app scope in place, Innowise defines the tech stack, designs the architecture, estimates timelines, and maps out core milestones.<\/p>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">\n                Design\n            <\/span>\n            <p class=\"new-step-item-text\">Innowise\u2019s UX\/UI designers create sleek wireframes, user flows, and prototypes to make your fitness app look great across mobile devices.<\/p>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">\n                Development\n            <\/span>\n            <p class=\"new-step-item-text\">Working in Agile iterations, our fitness app development targets all mobile platforms, focusing on code quality and seamless integrations.<\/p>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">\n                Testing\n            <\/span>\n            <p class=\"new-step-item-text\">Our QAs run manual and automated tests to catch bugs fast and make sure the fitness app works smoothly, without issues in the production environment.<\/p>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">Deployment\n            <\/span>\n            <p class=\"new-step-item-text\">Once everything\u2019s ready, we deploy the software, publish it to the App Store and\/or Google Play, and closely track its performance after the launch day.<\/p>\n        <\/div>\n    <\/div>\n\n\n    <div class=\"new-step-item\">\n        <div class=\"figure-container\">\n            <div class=\"scheme-progress-circle\">\n\n            <\/div>\n        <\/div>\n        <div class=\"new-step-item-desc\">\n            <span class=\"new-step-item-title\">Maintenance<\/span>\n            <p class=\"new-step-item-text\">Updates, features, security patches, and performance fixes \u2014 we help you with these things to keep the fitness app running smoothly long after go-live.<\/p>\n        <\/div>\n    <\/div>\n\n\n<\/div>\n\n\n<script>\n    (() => {\n\n        \/\/ number of elements must be at least equal to num of colors to work\n        const colors = [\n            \"#C63031\",\n            \"#CD505D\",\n            \"#D36F89\",\n            \"#DD9ECB\",\n            \"#E4BEF7\",\n            \"#BF9FD8\",\n            \"#A481BF\",\n        ]\n\n        const desktopFigures = [...document.querySelectorAll(\".roadmap-grid-2 .new-steps-container .figure-container\")]\n\n        desktopFigures.forEach((item, index) => {\n            item.style.setProperty(\"--item-color\", colors[index]);\n            \n            if (index >= 1) {\n                item.style.setProperty(\"--prev-item-color\", colors[index-1]);\n            }\n        })\n\n    })()\n<\/script>\n\n\n\n\n\n\n\n\n\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c123c6d e-grid e-con-full e-con e-child\" data-id=\"c123c6d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-82734d0 e-con-full e-flex e-con e-child\" data-id=\"82734d0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6752f0 img900500 elementor-widget elementor-widget-image\" data-id=\"c6752f0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1350\" height=\"750\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3.jpg\" class=\"attachment-full size-full wp-image-182131\" alt=\"OUR TEAM\" srcset=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3.jpg 1350w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3-300x167.jpg 300w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3-1024x569.jpg 1024w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3-768x427.jpg 768w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/04\/Team-Innowise-3-18x10.jpg 18w\" sizes=\"(max-width: 1350px) 100vw, 1350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1422a2a e-con-full e-flex e-con e-child\" data-id=\"1422a2a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c5fe762 e-con-full e-flex e-con e-child\" data-id=\"c5fe762\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84d5d6a elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"84d5d6a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Leading-edge fitness apps, rolled out without delays<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d020ed elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial tabletmax510 elementor-widget elementor-widget-text-editor\" data-id=\"2d020ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sounds like a dream? Not to Innowise: we launch apps within agreed timelines.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c364de elementor-align-center contact320 elementor-widget elementor-widget-button\" data-id=\"5c364de\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Let\u2019s talk<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d8d377 e-flex e-con-boxed e-con e-parent\" data-id=\"8d8d377\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75bad52 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"75bad52\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technologies we use for health and fitness app development\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24f221b elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"24f221b\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"technologies-content\">\r\n  <div class=\"technologies-content-body\">\r\n    <div class=\"technologies-content-body-menu\">\r\n      <div class=\"technologies-content-body-menu-item technologies_menu clickMenu active\" section=\"1\" content=\"technologies\">Frontend<\/div>\r\n      <div class=\"technologies-content-body-menu-item technologies_menu clickMenu\" section=\"2\" content=\"technologies\">Backend<\/div>\r\n      <div class=\"technologies-content-body-menu-item technologies_menu clickMenu\" section=\"3\" content=\"technologies\">Mobile<\/div>\r\n      <div class=\"technologies-content-body-menu-item technologies_menu clickMenu\" section=\"4\" content=\"technologies\">Cloud & Platforms<\/div>\r\n    <\/div>\r\n    <div class='technologiesSwiper'>\r\n      <div class='swiper-wrapper'>\r\n        <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_1 swiper-slide-active\">\r\n          <a href=\"https:\/\/innowise.com\/services\/front-end-development\/\"  class=\"technologies-content-body-information-title\">Frontend<\/a>\r\n          <div class=\"technologies-content-body-information-items\">\r\n            <a href='https:\/\/innowise.com\/technologies\/react-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">React<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Default.svg\" alt=\"react\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/angular-development\/'  class=\"grid-item black\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Angular<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Angular.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/vuejs-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Vue.js<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant3.svg\" alt=\"vue\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/javascript-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">JavaScript<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\"  src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/JavaScript.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n        <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_2\">\r\n          <a href=\"https:\/\/innowise.com\/services\/back-end-development\/\"  class=\"technologies-content-body-information-title\">Backend<\/a>\r\n          <div class=\"technologies-content-body-information-items\">\r\n            <a href='https:\/\/innowise.com\/technologies\/java-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Java<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Java-1.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/dot-net-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">.NET<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/NET.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/python-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Python<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant12.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/php-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">PHP<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/PHP.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/nodejs-development\/'  class=\"grid-item\">\r\n              <div class=\"block-technologies\" >\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Node.js<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant6.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/unity-development\/'  class=\"grid-item black\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Unity<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/unity.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/ruby-on-rails-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Ruby<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant8.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href=https:\/\/innowise.com\/technologies\/golang-development\/  class=\"grid-item\">\r\n              <div class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Go<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant18.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/rust-development\/'  class=\"grid-item black\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Rust<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Rust.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/c-plus-plus-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">C\/C++<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/11\/icon-2-1.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/unreal-engine-development\/'  class=\"grid-item black\">\r\n              <div class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Unreal Engine<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Unreal-Engine.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/cobol-development\/'  class=\"grid-item black\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Cobol<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/cobol.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n        <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_3\">\r\n          <a href=\"https:\/\/innowise.com\/services\/mobile-application-development\/\"  class=\"technologies-content-body-information-title\">Mobile<\/a>\r\n          <div class=\"technologies-content-body-information-items\">\r\n            <a  href='https:\/\/innowise.com\/services\/mobile-application-development\/ios\/'  class=\"grid-item black\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">iOS<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant16.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/services\/mobile-application-development\/android\/'  class=\"grid-item\">\r\n              <div class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Android<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant14.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/flutter-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Flutter<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant11.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/react-native-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">React Native<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Default.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\r\n        <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_4\">\r\n          <a href=\"https:\/\/innowise.com\/services\/cloud-development\/\"  class=\"technologies-content-body-information-title\">Cloud & Platforms<\/a>\r\n          <div class=\"technologies-content-body-information-items\">\r\n            <a href='https:\/\/innowise.com\/technologies\/aws\/'  class=\"grid-item\">\r\n              <div class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">AWS<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/AWS.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/azure\/'  class=\"grid-item\">\r\n              <div class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Azure<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Microsoft-Azure.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/google-cloud-platform\/'  class=\"grid-item\">\r\n              <div class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">GCP<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Google-Cloud-Platform-GCP.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/services\/erp\/sap\/'  class=\"grid-item\">\r\n                     <div  class=\"block-technologies\">\r\n                        <div class=\"block-technologies-text\">\r\n                           <div class=\"block-technologies-text-title\">SAP<\/div>\r\n                        <\/div>\r\n                        <div class=\"block-technologies-addition\">\r\n                           <div class=\"block-technologies-addition-icon\">\r\n                              <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/SAP.svg\" alt=\"\">\r\n                           <\/div>\r\n                        <\/div>\r\n                     <\/div>\r\n                  <\/a>\r\n\r\n  <a href='https:\/\/innowise.com\/services\/crm\/salesforce\/'  class=\"grid-item\">\r\n                     <div  class=\"block-technologies\">\r\n                        <div class=\"block-technologies-text\">\r\n                           <div class=\"block-technologies-text-title\">Salesforce<\/div>\r\n                        <\/div>\r\n                        <div class=\"block-technologies-addition\">\r\n                           <div class=\"block-technologies-addition-icon\">\r\n                              <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/salesforce.png\" alt=\"\">\r\n                           <\/div>\r\n                        <\/div>\r\n                     <\/div>\r\n                  <\/a>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\r\n<script>\r\n  document.addEventListener('DOMContentLoaded', () => {\r\n      \r\n    const technologiesSwiper = new Swiper('.technologiesSwiper', {\r\n        effect:'fade',\r\n      slidesPerView: 1,\r\n     spaceBetween: 24, \r\n  \r\n      allowTouchMove:false,   \r\n         \r\n    });  \r\n      \r\n  \r\n  const technologiesListItems = document.querySelectorAll(\r\n    '.technologies-content-body-menu-item'\r\n  );\r\n  \r\n  \r\n  \r\n  \r\n  \r\n  \r\n  \r\n  \r\n  \r\n  technologiesListItems.forEach((listItem, index, arr) => {\r\n      \r\n    listItem.addEventListener('click', () => {\r\n      arr.forEach((item,i) => {\r\n        if (item === listItem) {\r\n          item.classList.add('active');\r\n          technologiesSwiper.slideTo(i);\r\n        } else {\r\n          item.classList.remove('active');\r\n        }\r\n      });\r\n      \r\n    });\r\n  });\r\n  \r\n  \r\n  \r\n  \r\n  \r\n  });\r\n  \r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7213e84 rating-table-topRated elementor-hidden-desktop elementor-widget elementor-widget-n-accordion\" data-id=\"7213e84\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1190\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-1190\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Frontend <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1190\" class=\"elementor-element elementor-element-399070d e-con-full e-flex e-con e-child\" data-id=\"399070d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b03408 elementor-widget elementor-widget-html\" data-id=\"0b03408\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                <div class=\"technologies-content-body-information-items\">\n                    <a href='https:\/\/innowise.com\/technologies\/react-development\/' class=\"grid-item\">\n                        <div  class=\"block-technologies\">\n                            <div class=\"block-technologies-text\">\n                                <div class=\"block-technologies-text-title\">React<\/div>\n                                \n                            <\/div>\n                            <div class=\"block-technologies-addition\">\n                                <div class=\"block-technologies-addition-icon\">\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Default.svg\" alt=\"react\">\n                                <\/div>\n\n                                  \n                            <\/div>\n                        <\/div>\n                    <\/a>\n                    <a href='https:\/\/innowise.com\/technologies\/angular-development\/'  class=\"grid-item black\">\n                        <div  class=\"block-technologies\">\n                            <div class=\"block-technologies-text\">\n                                <div class=\"block-technologies-text-title\">Angular<\/div>\n                                \n                            <\/div>\n                            <div class=\"block-technologies-addition\">\n                                <div class=\"block-technologies-addition-icon\">\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Angular.svg\" alt=\"\">\n                                <\/div>\n\n                                 \n                            <\/div>\n                        <\/div>\n                    <\/a>\n                    <a href='https:\/\/innowise.com\/technologies\/vuejs-development\/' class=\"grid-item\">\n                        <div  class=\"block-technologies\">\n                            <div class=\"block-technologies-text\">\n                                <div class=\"block-technologies-text-title\">Vue.js<\/div>\n                                \n                            <\/div>\n                            <div class=\"block-technologies-addition\">\n                                <div class=\"block-technologies-addition-icon\">\n                                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant3.svg\" alt=\"vue\">\n                                <\/div>\n                                \n                            <\/div>\n                        <\/div>\n                    <\/a>\n                    <a href='https:\/\/innowise.com\/technologies\/javascript-development\/' class=\"grid-item\">\n                        <div  class=\"block-technologies\">\n                            <div class=\"block-technologies-text\">\n                                <div class=\"block-technologies-text-title\">JavaScript<\/div>\n                                \n                                \n                            <\/div>\n                            <div class=\"block-technologies-addition\">\n                                <div class=\"block-technologies-addition-icon\">\n                                    <img decoding=\"async\"  src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/JavaScript.svg\" alt=\"\">\n                                <\/div>\n                                \n                            <\/div>\n                        <\/div>\n                    <\/a>\n                        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1191\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1191\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Backend <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1191\" class=\"elementor-element elementor-element-ebaa2bb e-con-full e-flex e-con e-child\" data-id=\"ebaa2bb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cd613e elementor-widget elementor-widget-html\" data-id=\"4cd613e\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t <div class=\"technologies-content-body-information technologies_section swiper-slide technologies_2\">\r\n          <div class=\"technologies-content-body-information-items\">\r\n            <a href='https:\/\/innowise.com\/technologies\/java-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Java<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Java-1.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/dot-net-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">.NET<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/NET.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/python-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Python<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant12.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/php-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">PHP<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/PHP.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/nodejs-development\/'  class=\"grid-item\">\r\n              <div class=\"block-technologies\" >\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Node.js<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant6.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/unity-development\/'  class=\"grid-item black\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Unity<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/unity.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/ruby-on-rails-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Ruby<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant8.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href=https:\/\/innowise.com\/technologies\/golang-development\/  class=\"grid-item\">\r\n              <div class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Go<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant18.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/rust-development\/'  class=\"grid-item black\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Rust<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Rust.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/c-plus-plus-development\/'  class=\"grid-item\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">C\/C++<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/11\/icon-2-1.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/unreal-engine-development\/'  class=\"grid-item black\">\r\n              <div class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Unreal Engine<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Unreal-Engine.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n            <a href='https:\/\/innowise.com\/technologies\/cobol-development\/'  class=\"grid-item black\">\r\n              <div  class=\"block-technologies\">\r\n                <div class=\"block-technologies-text\">\r\n                  <div class=\"block-technologies-text-title\">Cobol<\/div>\r\n                <\/div>\r\n                <div class=\"block-technologies-addition\">\r\n                  <div class=\"block-technologies-addition-icon\">\r\n                    <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/cobol.svg\" alt=\"\">\r\n                  <\/div>\r\n                <\/div>\r\n              <\/div>\r\n            <\/a>\r\n          <\/div>\r\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1192\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1192\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Mobile <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1192\" class=\"elementor-element elementor-element-abc39f5 e-con-full e-flex e-con e-child\" data-id=\"abc39f5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-294ac6d elementor-widget elementor-widget-html\" data-id=\"294ac6d\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"technologies-content-body-information-items\">\r\n  <a  href='https:\/\/innowise.com\/services\/mobile-application-development\/ios\/' target=\"_blank\" class=\"grid-item black\">\r\n    <div  class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">iOS<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant16.svg\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n  <a href='https:\/\/innowise.com\/services\/mobile-application-development\/android\/' target=\"_blank\" class=\"grid-item\">\r\n    <div class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">Android<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant14.svg\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n  <a href='https:\/\/innowise.com\/technologies\/flutter-development\/' target=\"_blank\" class=\"grid-item\">\r\n    <div  class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">Flutter<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Variant11.svg\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n  <a href='https:\/\/innowise.com\/technologies\/react-native-development\/' target=\"_blank\" class=\"grid-item\">\r\n    <div  class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">React Native<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/06\/Property-1Default.svg\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1193\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1193\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Cloud &amp; Platforms <\/div><\/span>\n\t\t\t\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1193\" class=\"elementor-element elementor-element-4f993f9 e-con-full e-flex e-con e-child\" data-id=\"4f993f9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a495098 elementor-widget elementor-widget-html\" data-id=\"a495098\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"technologies-content-body-information-items\">\r\n  <a href='https:\/\/innowise.com\/technologies\/aws\/' target=\"_blank\" class=\"grid-item\">\r\n    <div class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">AWS<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/AWS.svg\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n  <a href='https:\/\/innowise.com\/technologies\/azure\/' target=\"_blank\" class=\"grid-item\">\r\n    <div class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">Azure<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Microsoft-Azure.svg\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n  <a href='https:\/\/innowise.com\/technologies\/google-cloud-platform\/' target=\"_blank\" class=\"grid-item\">\r\n    <div class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">GCP<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/Google-Cloud-Platform-GCP.svg\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n  <a href='https:\/\/innowise.com\/services\/erp\/sap\/' target=\"_blank\" class=\"grid-item\">\r\n    <div  class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">SAP<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/12\/SAP.svg\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n  <a href='https:\/\/innowise.com\/services\/crm\/salesforce\/' target=\"_blank\" class=\"grid-item\">\r\n    <div  class=\"block-technologies\">\r\n      <div class=\"block-technologies-text\">\r\n        <div class=\"block-technologies-text-title\">Salesforce<\/div>\r\n      <\/div>\r\n      <div class=\"block-technologies-addition\">\r\n        <div class=\"block-technologies-addition-icon\">\r\n          <img decoding=\"async\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/salesforce.png\" alt=\"\">\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e390b09 e-flex e-con-boxed e-con e-parent\" data-id=\"e390b09\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6e3f059 e-con-full e-flex e-con e-child\" data-id=\"6e3f059\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a97c90 elementor-widget elementor-widget-heading\" data-id=\"0a97c90\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Choose Innowise as your fitness app development company<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffbd613 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"ffbd613\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A mature fitness application development company, Innowise has built 60+ apps that go far beyond step counters and truly stand out on the market. We blend technical depth with industry know-how to deliver scalable, engaging, user-focused solutions that align with your business goals.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-695e3f3 e-con-full e-flex e-con e-child\" data-id=\"695e3f3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a9d399 elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-video\" data-id=\"5a9d399\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=-ezRzXe5Sz0&amp;t=1s&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6322d7d e-grid e-con-full e-con e-child\" data-id=\"6322d7d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c906988 e-con-full e-flex e-con e-child\" data-id=\"c906988\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfa4e0c imgMobile240 elementor-widget elementor-widget-image\" data-id=\"cfa4e0c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"669\" height=\"470\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/09\/Frame-1597885559-2-1.png\" class=\"attachment-full size-full wp-image-187912\" alt=\"\" srcset=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/09\/Frame-1597885559-2-1.png 669w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/09\/Frame-1597885559-2-1-300x211.png 300w, https:\/\/innowise.com\/wp-content\/uploads\/2025\/09\/Frame-1597885559-2-1-18x12.png 18w\" sizes=\"(max-width: 669px) 100vw, 669px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60d0dc5 e-con-full e-flex e-con e-child\" data-id=\"60d0dc5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-f7cfb4f e-con-full e-flex e-con e-child\" data-id=\"f7cfb4f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c34919 elementor-widget__width-initial word-wrap-title elementor-widget elementor-widget-heading\" data-id=\"5c34919\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Don\u2019t guesstimate the cost of your fitness app\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc4ad6a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial tabletmax510 elementor-widget elementor-widget-text-editor\" data-id=\"fc4ad6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our experts will analyze your needs and share a detailed cost calculation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-206a970 elementor-align-center contact320 elementor-widget elementor-widget-button\" data-id=\"206a970\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get a quote<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32d2c50 e-flex e-con-boxed e-con e-parent\" data-id=\"32d2c50\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1eca8c elementor-widget elementor-widget-heading\" data-id=\"c1eca8c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What our customers think<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fe72cd elementor-widget elementor-widget-html\" data-id=\"9fe72cd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"c-section__background\">\r\n  <div class=\"c-section__container p-mad-testimonials__section-container\">\r\n    <div class=\"c-section__body\">\r\n\r\n      <div class=\"p-mad-testimonials__swiper\">\r\n        <div class=\"swiper\">\r\n          <div class=\"swiper-wrapper\">\r\n\r\n            <div class=\"swiper-slide p-mad-testimonial\">\r\n              <div class=\"p-mad-testimonial__cite-author\">\r\n                <div class=\"p-mad-testimonial__author\">\r\n                  <span class=\"p-mad-testimonial__author-name\">Dr. Felix Berthelmann<\/span>\r\n                  <span>Managing Director<\/span>\r\n                  <span>Digital Science<\/span>\r\n                <\/div>\r\n                <div class=\"p-mad-testimonial__company-icon-wrapper\">\r\n                  <img decoding=\"async\" class=\"p-mad-testimonial__company-icon\"\r\n                    src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/Digital-science.png\"\r\n                    alt=\"Digital Science logo\">\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"p-mad-testimonial__cite-details\">\r\n                <p class=\"p-mad-testimonial__cite\">\r\n                  \u201cOver the years, Innowise has consistently proven to be a long-term reliable partner. The consistency and quality of the services provided have significantly contributed to the success of our joint initiatives.\u201d\r\n                <\/p>\r\n                <ul class=\"p-mad-testimonial__details\">\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Industry<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">Healthcare, Pharma, Life Sciences<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Team size<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">2 specialists<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Duration<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">44 months<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Services<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">Staff augmentation, Data science<\/span>\r\n                  <\/li>\r\n                <\/ul>\r\n              <\/div>\r\n            <\/div>\r\n\r\n            <div class=\"swiper-slide p-mad-testimonial\">\r\n              <div class=\"p-mad-testimonial__cite-author\">\r\n                <div class=\"p-mad-testimonial__author\">\r\n                  <span class=\"p-mad-testimonial__author-name\">Wilman Vergara, MHI<\/span>\r\n                  <span>Founder & CEO<\/span>\r\n                  <span>KNOSIS Health, LLC<\/span>\r\n                <\/div>\r\n                <div class=\"p-mad-testimonial__company-icon-wrapper\">\r\n                  <img decoding=\"async\" class=\"p-mad-testimonial__company-icon\"\r\n                    src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/05\/Oknosis.png\"\r\n                    alt=\"KNOSIS Health logo\">\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"p-mad-testimonial__cite-details\">\r\n                <p class=\"p-mad-testimonial__cite\">\r\n                  \u201cTheir US Director and Project Manager were very timely with their responses and\/or requests. The time difference was a bit of a challenge but that was overcome by the quality of their work. Quick, efficient, and very professional. I would highly recommend.\u201d\r\n                <\/p>\r\n                <ul class=\"p-mad-testimonial__details\">\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Industry<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">Healthcare, Pharma, Life Sciences<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Team size<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">4 specialists<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Duration<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">33+ months<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Services<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">AR, Healthcare, Sport, Fitness<\/span>\r\n                  <\/li>\r\n                <\/ul>\r\n              <\/div>\r\n            <\/div>\r\n\r\n            <div class=\"swiper-slide p-mad-testimonial\">\r\n              <div class=\"p-mad-testimonial__cite-author\">\r\n                <div class=\"p-mad-testimonial__author\">\r\n                  <span class=\"p-mad-testimonial__author-name\">Dr. Udo Richter<\/span>\r\n                  <span>Director<\/span>\r\n                  <span>n:aip<\/span>\r\n                <\/div>\r\n                <div class=\"p-mad-testimonial__company-icon-wrapper\">\r\n                  <img decoding=\"async\" class=\"p-mad-testimonial__company-icon\"\r\n                    src=\"https:\/\/innowise.com\/wp-content\/uploads\/2025\/06\/n_aip.png\"\r\n                    alt=\"n:aip logo\">\r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"p-mad-testimonial__cite-details\">\r\n                <p class=\"p-mad-testimonial__cite\">\r\n                  \u201cInnowise was selected due to its extensive experience of developing complex medical solutions. They managed to quickly and effectively put together a team of IT-specialists. Innowise is characterized by efficient and professional organization of its operation practices.\u201d\r\n                <\/p>\r\n                <ul class=\"p-mad-testimonial__details\">\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Industry<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">Healthcare<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Team size<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">4 specialists<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Duration<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">60+ months<\/span>\r\n                  <\/li>\r\n                  <li>\r\n                    <span class=\"p-mad-testimonial__details-term\">Services<\/span>\r\n                    <span class=\"p-mad-testimonial__details-desc\">Software modernization<\/span>\r\n                  <\/li>\r\n                <\/ul>\r\n              <\/div>\r\n            <\/div>\r\n\r\n          <\/div>\r\n          <div class=\"swiper-pagination\"><\/div>\r\n\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>\r\n\r\n\r\n  \r\n  <script>\r\n  const options = {\r\n    grabCursor: true,\r\n    slidesPerView: 'auto',\r\n    spaceBetween: 20,\r\n    pagination: {\r\n      el: '.p-mad-testimonials__swiper .swiper-pagination',\r\n      clickable:true,\r\n    },\r\n    breakpoints: {\r\n       200: {\r\n        spaceBetween: 20\r\n       },\r\n       768: {\r\n        spaceBetween: 40\r\n       },\r\n      },\r\n  };\r\n  \r\n  let customerReviewsSwiper = new Swiper(\r\n    '.p-mad-testimonials__swiper .swiper',\r\n    options,\r\n  );\r\n  \r\n  customerReviewsSwiper.autoplay.stop();\r\n  \r\n  <\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f50d6a e-flex e-con-boxed e-con e-parent\" data-id=\"3f50d6a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dcb3ba2 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"dcb3ba2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Frequently asked questions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af4cbc9 e-con-full e-grid e-con e-child\" data-id=\"af4cbc9\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-878a2be e-con-full e-flex e-con e-child\" data-id=\"878a2be\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c42d7fd elementor-widget elementor-widget-html\" data-id=\"c42d7fd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"c-accordion faq-accord\">\r\n\r\n  <div class=\"c-accordion__item\">\r\n    <div class=\"c-accordion__trigger tech-accord-trigger\">\r\n      <div class=\"c-accordion__header\">\r\n        <button class=\"c-accordion__toggle-button\">\r\n          <img decoding=\"async\" class='plus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/open-accordion.svg\" alt=\"toggle-icon\">\r\n          <img decoding=\"async\" class='minus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/close-accordion.svg\" alt=\"toggle-icon\">\r\n        <\/button>\r\n        <span class=\"c-accordion__title\">How long does it take to develop a fitness app?<\/span>\r\n      <\/div>\r\n\r\n      <div class=\"c-accordion__panel p-mad-tech-stack__details\">\r\n        <div class='content'>\r\n          Health and fitness apps development timelines vary from project to project, with the most popular reasons for it being software scope, complexity, and required integrations. On average, it takes 3 months or more to launch an MVP (minimum viable product) of a fitness app. If you need to better understand the timeline of your project, just <a href=\"#contact-form\">text us<\/a>, and Innowise\u2019s experts will make realistic estimates.\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"c-accordion__item\">\r\n    <div class=\"c-accordion__trigger tech-accord-trigger\">\r\n      <div class=\"c-accordion__header\">\r\n        <button class=\"c-accordion__toggle-button\">\r\n          <img decoding=\"async\" class='plus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/open-accordion.svg\" alt=\"toggle-icon\">\r\n          <img decoding=\"async\" class='minus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/close-accordion.svg\" alt=\"toggle-icon\">\r\n        <\/button>\r\n        <span class=\"c-accordion__title\">How can my fitness app be monetized?<\/span>\r\n      <\/div>\r\n\r\n      <div class=\"c-accordion__panel p-mad-tech-stack__details\">\r\n        <div class='content'>\r\n          There\u2019s a range of monetization models out there: subscription tiers, in-app purchases, premium content, brand advertising, and others. During the discovery phase, Innowise\u2019s experts will help you explore options that match the target audience of your fitness app and overall business goals, and implement monetization features into the final software.\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"c-accordion__item\">\r\n    <div class=\"c-accordion__trigger tech-accord-trigger\">\r\n      <div class=\"c-accordion__header\">\r\n        <button class=\"c-accordion__toggle-button\">\r\n          <img decoding=\"async\" class='plus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/open-accordion.svg\" alt=\"toggle-icon\">\r\n          <img decoding=\"async\" class='minus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/close-accordion.svg\" alt=\"toggle-icon\">\r\n        <\/button>\r\n        <span class=\"c-accordion__title\">Can I customize the features and design of my fitness app?<\/span>\r\n      <\/div>\r\n\r\n      <div class=\"c-accordion__panel p-mad-tech-stack__details\">\r\n        <div class='content'>\r\n          Absolutely. We are not offering out-of-the-box solutions, we fully tailor functionality and UI to fit your brand and vision. Innowise\u2019s team will help you bring your vision to reality, whether you need a simple and sleek app or advanced software with AI coaching, smart nutrition modules, or video analytics.\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"c-accordion__item\">\r\n    <div class=\"c-accordion__trigger tech-accord-trigger\">\r\n      <div class=\"c-accordion__header\">\r\n        <button class=\"c-accordion__toggle-button\">\r\n          <img decoding=\"async\" class='plus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/open-accordion.svg\" alt=\"toggle-icon\">\r\n          <img decoding=\"async\" class='minus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/close-accordion.svg\" alt=\"toggle-icon\">\r\n        <\/button>\r\n        <span class=\"c-accordion__title\">Can you integrate wearable devices with the fitness app?<\/span>\r\n      <\/div>\r\n\r\n      <div class=\"c-accordion__panel p-mad-tech-stack__details\">\r\n        <div class='content'>\r\n          Sure, our health and fitness app development company is experienced at integrating apps with smartwatches, fitness bands, IoT sensors, and other devices. Our apps sync with devices and get real-time health and activity data to enable performance tracking, goal setting, and personalized feedback based on accurate metrics.\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"c-accordion__item\">\r\n    <div class=\"c-accordion__trigger tech-accord-trigger\">\r\n      <div class=\"c-accordion__header\">\r\n        <button class=\"c-accordion__toggle-button\">\r\n          <img decoding=\"async\" class='plus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/open-accordion.svg\" alt=\"toggle-icon\">\r\n          <img decoding=\"async\" class='minus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/close-accordion.svg\" alt=\"toggle-icon\">\r\n        <\/button>\r\n        <span class=\"c-accordion__title\">How do you ensure the security and privacy of user data in the fitness app?<\/span>\r\n      <\/div>\r\n\r\n      <div class=\"c-accordion__panel p-mad-tech-stack__details\">\r\n        <div class='content'>\r\n          To protect sensitive data, Innowise\u2019s health and fitness app developers implement industry best practices, like end-to-end data encryption, role-based access, multifactor authentication, and secure APIs. When HIPAA or GDPR apply, we follow these regulatory requirements precisely. Furthermore, Innowise is ISO 27001 certified, meaning we are well-equipped to handle data securely.\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"c-accordion__item\">\r\n    <div class=\"c-accordion__trigger tech-accord-trigger\">\r\n      <div class=\"c-accordion__header\">\r\n        <button class=\"c-accordion__toggle-button\">\r\n          <img decoding=\"async\" class='plus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/open-accordion.svg\" alt=\"toggle-icon\">\r\n          <img decoding=\"async\" class='minus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/close-accordion.svg\" alt=\"toggle-icon\">\r\n        <\/button>\r\n        <span class=\"c-accordion__title\">Will the fitness app be available on both iOS and Android platforms?<\/span>\r\n      <\/div>\r\n\r\n      <div class=\"c-accordion__panel p-mad-tech-stack__details\">\r\n        <div class='content'>\r\n          Absolutely. We offer both native and cross-platform fitness app development depending on your needs. That means your app can work seamlessly on both iOS and Android devices. When Innowise\u2019s consultants and fitness app developers plan out your solution, they help you decide on the best platforms and development options for your business.\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n  <div class=\"c-accordion__item\">\r\n    <div class=\"c-accordion__trigger tech-accord-trigger\">\r\n      <div class=\"c-accordion__header\">\r\n        <button class=\"c-accordion__toggle-button\">\r\n          <img decoding=\"async\" class='plus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/open-accordion.svg\" alt=\"toggle-icon\">\r\n          <img decoding=\"async\" class='minus' src=\"https:\/\/innowise.com\/wp-content\/uploads\/2022\/02\/close-accordion.svg\" alt=\"toggle-icon\">\r\n        <\/button>\r\n        <span class=\"c-accordion__title\">How can I get started with developing my fitness app?<\/span>\r\n      <\/div>\r\n\r\n      <div class=\"c-accordion__panel p-mad-tech-stack__details\">\r\n        <div class='content'>\r\n          You\u2019re welcome to just reach out to us. We\u2019ll start with a discovery call to learn more about your goals, then offer cost calculations, timelines, and the best-fit team to move forward.\r\n        <\/div>\r\n      <\/div>\r\n    <\/div>\r\n  <\/div>\r\n\r\n<\/div>\r\n\r\n\r\n<script defer src=\"\/wp-content\/themes\/hello-elementor\/assets\/js\/accordion.min.js\"><\/script>\r\n\r\n<script defer>\r\n  window.addEventListener(\"DOMContentLoaded\", (event) => {\r\n    new Accordion('.faq-accord', {\r\n      duration: 400,\r\n      showMultiple: false,\r\n      elementClass: 'c-accordion__item',\r\n      triggerClass: 'c-accordion__trigger',\r\n      panelClass: 'c-accordion__panel',\r\n      activeClass: 'active',\r\n    });\r\n  });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-169b06a elementor-widget elementor-widget-html\" data-id=\"169b06a\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\r\n  .showMore-btn {\r\n    display: flex;\r\n    justify-content: start;\r\n    width: fit-content;\r\n    margin: 40px 0 40px 20px;\r\n    cursor: pointer;\r\n    box-sizing: border-box;\r\n    height: 20px;\r\n  }\r\n\r\n  .showMore-btn span {\r\n    font-family: 'Sora';\r\n    font-style: normal;\r\n    font-weight: 600;\r\n    font-size: 18px;\r\n    line-height: 130%;\r\n    color: #C63031;\r\n  }\r\n\r\n  .showMore-btn:hover {\r\n    border-bottom: 1px solid #C63031;\r\n  }\r\n\r\n\r\n    .showMore-btn.active>span:nth-child(1) {\r\n      display: none;\r\n    }\r\n\r\n    .showMore-btn.active>span:nth-child(2) {\r\n      display: block;\r\n    }\r\n\r\n    .showMore-btn>span:nth-child(2) {\r\n      display: none;\r\n    }\r\n\r\n    .c-accordion.faq-accord > div:nth-child(n+5) {\r\n      display: none;\r\n    }\r\n\r\n    .c-accordion.faq-accord.active > div:nth-child(n+5) {\r\n      display: flex;\r\n    }\r\n  @media(max-width: 767px) {\r\n    .showMore-btn {\r\n      margin: 20px 0 0 0;\r\n    }\r\n    \r\n    .showMore-btn span{\r\n        font-size: 14px;\r\n    }\r\n  }\r\n<\/style>\r\n<div class=\"showMore-btn\">\r\n  <span>Show more<\/span>\r\n  <span>Show less<\/span>\r\n<\/div>\r\n\r\n<script defer>\r\njQuery(document).ready(function () {\r\n  const showMoreBtn = jQuery(\".showMore-btn\");\r\n  const wrapperBlock = jQuery(\".c-accordion.faq-accord\");\r\n     const anchor = jQuery(\".c-accordion.faq-accord div:nth-child(1)\");\r\n     const initialPosition = {\r\n       top: anchor.offset().top,\r\n     };\r\n\r\n  showMoreBtn.click(function (e) {\r\n    if (showMoreBtn.hasClass(\"active\")) {\r\n      jQuery(\"html, body\").animate({\r\n        scrollTop: initialPosition.top,\r\n      }, 200);\r\n    }\r\n    wrapperBlock.toggleClass(\"active\");\r\n    showMoreBtn.toggleClass(\"active\");\r\n  });\r\n });\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c732f42 e-con-full e-flex e-con e-child\" data-id=\"c732f42\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-90cb0a8 e-con-full maxHeight516 e-flex e-con e-child\" data-id=\"90cb0a8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15935c8 elementor-widget elementor-widget-image\" data-id=\"15935c8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/innowise.com\/wp-content\/uploads\/2024\/10\/Customer-service.svg\" class=\"attachment-full size-full wp-image-173854\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7cc64df e-con-full e-flex e-con e-child\" data-id=\"7cc64df\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ad80c4 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"4ad80c4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Feel free to book a call and get all the answers you need.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd8e819 elementor-widget__width-inherit ctaSecond elementor-widget-tablet__width-initial elementor-widget elementor-widget-button\" data-id=\"fd8e819\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact-form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Book a call<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a351c23 e-flex e-con-boxed e-con e-parent\" data-id=\"a351c23\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-253017e elementor-widget elementor-widget-shortcode\" data-id=\"253017e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f100240-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"100240\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/sv\/wp-json\/wp\/v2\/pages\/137927#wpcf7-f100240-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"100240\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f100240-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<style>\n.mailToContact br:nth-child(2){\ndisplay:none;\n}\n#form-templates .contact__info {\n  background-color: #f4f4f4;\n  padding: 70px 44px 70px 50px;\n  position: relative;\n  max-width: 540px;\n  width: 100%;\nborder: 1px solid #AEB1B7;\n}\n\n#form-templates .contact__info-background {\n  z-index: -1;\n  position: absolute;\n  top: 20px;\n  left: 20px;\n  width: 100%;\n  height: 100%;\n  border: 1px dashed #ef4557;\n}\n\n\n#form-templates .new-container{\ndisplay: flex;\njustify-content: space-between;\nflex-wrap: wrap;\n}\n\n\n#form-templates{\npadding: 100px 15px 100px 15px;        \n}\n\n#form-templates .contact__info-heading {\n  font-family: 'Sora' !important;\n  font-style: normal !important;\n  font-weight: 400 !important;\n  font-size: 36px !important;\n  line-height: 46px !important;\n  color: #2E2E2E !important;\n   margin-bottom: 60px !important;\n\n}\n\n\n#form-templates .message label{\ncolor: #585858 !important;   \n}\n\n.elementor-widget-container.form-template h2,.elementor-widget-container.form-template h1{\n font-size: 60px !important;\n  line-height: 70px !important;\n  font-family: \"Sora\", Sans-serif;\n  font-weight: 400;\n  margin: 0;  \n  margin-bottom: 20px;\n}\n\n\n\n\n.elementor-widget-container.form-template p{\n  font-family: \"Karla\", Sans-serif;\n  font-size: 22px;\n  font-weight: 400;\n  line-height: 28px;\n  color: var( --e-global-color-primary );\n  max-width: 700px;\n  margin: 0; \n  margin-bottom: 40px;\n} \n  \n\n\n.new-container #spinner{\nwidth: 50%;\nmax-width: 700px;\n}\n\n\n#form-templates .new-container #spinner div.contact-us__wrapper:nth-child(6){\ngap:30px; \n    \n}\n\n\n#form-templates .contact__info-heading {\n  margin-bottom: 67px;\n  font-size: 36px;\n  font-family: karla;\n  color:  #2E2E2E;\n\n  line-height: 49px;\n}\n\n#form-templates .contact__info-steps {\n  display: flex;\n  flex-direction: column;\n  max-width: 425x;\n  row-gap: 20px;\n  border-left: 1px solid #2e2e2e;\n}\n\n#form-templates .contact__info-block {\n  position: relative;\n  padding-left: 45px;\n}\n\n#form-templates .contact__info-block:last-child {\n  box-shadow: -1px 0 0 1px #f4f4f4;\n}\n\n#form-templates .contact__info-step {\n  position: absolute;\n  border: 1px solid #2e2e2e;\n  width: 40px;\n  height: 40px;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  border-radius: 20px;\n  left: -20px;\n  top: -8px;\n  background-color: #F4F4F4;\n  color:  #2E2E2E;\n\nfont-family: Karla;\nfont-weight: 700;\nfont-size: 18px;\nline-height: 28px;\n\n}\n\n.elementor-widget-global .contact__info-step {\n        color:  #2E2E2E;\n}\n\n#form-templates .contact__info-text {\n  margin: 0;\n  font-size: 16px;\n  line-height: 26px;\n  color: #2E2E2E;\n  font-family: karla;\n\n  width: 100%;\n}\n\n\n#form-templates .contact-us__send{\nflex-shrink: 0;\nmargin-top:0;\n}\n\n\n\n@media screen and (max-width: 1279px) {\n    .new-container #spinner{\n        width: 100%;\n        max-width:100%;\n        margin-bottom:40px;\n    }\n    \n\n    .new-container .contact__info {\n        max-width: 700px !important;\n    }\n    \n}\n\n\n@media screen and (max-width: 1279px) {\n#form-templates{\npadding: 60px 15px 70px 15px;     \n}\n}\n\n\n\n@media screen and (max-width: 767px) {\n\n#form-templates .new-container #spinner div.contact-us__wrapper:nth-child(6){\ngap:20px; \n \n}\n\n\n  #form-templates .contact__info {\n    padding: 20px 20px 40px 40px;\n    margin: 0 auto;\n  }\n\n\n#form-templates{\npadding: 40px 15px 50px 15px;  \n    \n}\n\n  \n   .new-container #spinner{\n       \n    margin-bottom:30px;   \n   }\n   \n   \n   .elementor-widget-container #form-templates .form-template h2,.elementor-widget-container.form-template h1{\n   font-size: 32px !important;\n    line-height: 42px !important;    \n   }\n   \n   \n   .elementor-widget-container #form-templates .form-template p{\n       \n    font-size: 16px;\n    line-height: 20px;  \n    margin-bottom: 30px !important;\n \n       \n   }\n   \n   #form-templates .contact__info-heading{\n   font-size: 24px !important;\n    line-height: 49px !important;    \n       \n   }\n   \n\n.mailToContact{\nmargin-top: 10px !important;        \n}\n\n   \n\n  #form-templates .contact__info-heading {\n    font-size: 24px;\n    margin-bottom: 37px;\n  }\n\n  #form-templates .contact__info-background {\n    top: 10px;\n    left: 10px;\n  }\n\n  #form-templates .contact__info-text {\n    font-size: 12px;\n    line-height: 20px;\n  }\n  \n  \n  #form-templates .contact__info-heading {\n   margin-bottom: 35px !important;\n\n}\n\n}\n\n@media (max-width: 767px) {\n    .mailToContact {\n        max-width: 100%;\n    }\n    .contact-us__wrapper .pp {\nfont-size: 12px !important;\nline-height: 140%;\nmargin-bottom: 0 !important;\n\n}\n}\n<\/style>\n\n<script>\nwindow.addEventListener('hashchange',function(e){if(window.history.pushState){window.history.pushState('','\/',window.location.pathname)}else{window.location.hash=''}})\n<\/script>\n\n\n<div id=\"form-templates\">\n<div class=\"elementor-widget-container form-template\">\n<a name=\"contact-form\"><\/a>\n<h2>Contact us<\/h2>\n<p><a id=\"calendlylink\" style=\"color: #c63031; border-bottom: 1px solid #c63031; padding: 0;\">Book a call<\/a> or fill out the form below and we\u2019ll get back to you once we\u2019ve processed your request.<\/p>\n<\/div>\n\n<div class=\"new-container\">\n\n\n<div class=\"contact-us__main\" id=\"spinner\" data-no-defer=\"1\">\n\n<div class=\"contact-us__wrapper\">\n\n<div class=\"name\">\n<label>Name<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"field_name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required contact-us__name\" id=\"contact-name\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name*\" value=\"\" type=\"text\" name=\"field_name\" \/><\/span>\n<\/div>\n\n<div class=\"company\">\n<label>Company<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required contact-us__company\" id=\"contact-company\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company*\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n<\/div>\n\n<\/div>\n\n<div class=\"contact-us__wrapper\">\n\n<div class=\"email\">\n<label>Email<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email contact-us__email\" id=\"contact-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Corporate email*\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n<\/div>\n\n<div class=\"phone\">\n<label>Phone<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel contact-us__phone\" id=\"contact-phone\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone*\" value=\"\" type=\"tel\" name=\"tel\" \/><\/span>\n<\/div>\n\n<\/div>\n<div class=\"contact-us__wrapper subj\">\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-recipient\"><select class=\"wpcf7-form-control wpcf7-select\" id=\"form-field-subj_js\" aria-invalid=\"false\" name=\"your-recipient\"><option value=\"\">Subject*<\/option><option value=\"IT staff augmentation\">IT staff augmentation<\/option><option value=\"Turnkey product development\">Turnkey product development<\/option><option value=\"Support and enhancement\">Support and enhancement<\/option><option value=\"Careers\">Careers<\/option><option value=\"Other\">Other<\/option><\/select><\/span>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"form-field-budget_js\"><select class=\"wpcf7-form-control wpcf7-select\" id=\"form-field-budget_js\" aria-invalid=\"false\" name=\"form-field-budget_js\"><option value=\"\">Project budget<\/option><option value=\"Under $15K\">Under $15K<\/option><option value=\"$15K-$30K\">$15K-$30K<\/option><option value=\"$30K-$100K\">$30K-$100K<\/option><option value=\"$100K-$250K\">$100K-$250K<\/option><option value=\"$250K-$500K\">$250K-$500K<\/option><option value=\"More than $500K\">More than $500K<\/option><\/select><\/span>\n\n<\/div>\n\n\n<div class=\"message\">\n<label>Message<\/label>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"1\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required contact-us__message\" id=\"contact-message\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Describe your needs in detail*\" name=\"message\"><\/textarea><\/span>\n<\/div>\n\n<div class=\"atvoice-wrap\">\n\n<div class=\"voice-wrap\">\n<span id=\"voice-mut\" class=\"voicetext\">Send us a voice message<\/span>\n         <div class=\"qc_voice_audio_wrapper\">\n            <div class=\"qc_voice_audio_container\">\n                <div class=\"qc_voice_audio_upload_main\" id=\"qc_audio_main\">\n                    <a class=\"qc_audio_record_button\" id=\"qc_audio_record\" href=\"#\" aria-label=\"Record an audio message\">\n                        <span class=\"dashicons dashicons-microphone\"><\/span> \u00a0<\/a> \n                <\/div>\n\n                <div class=\"qc_voice_audio_recorder\" id=\"qc_audio_recorder\" style=\"display:none\">\n\n                <\/div>\n                <div class=\"qc_voice_audio_display\" id=\"qc_audio_display\"  style=\"display:none\">\n                    <audio id=\"qc-audio\" controls src=\"\"><\/audio>\n                    <span title=\"Remove and back to main upload screen.\" class=\"qc_audio_remove_button dashicons dashicons-trash\"><\/span>\n                <\/div>\n            <\/div>\n            <input type=\"hidden\" value=\"\" name=\"qcwpvoicemessage\" id=\"qc_audio_url\" \/>\n        <\/div>\n        \n<\/div>\n\n\n<div class=\"attach-wrap\">\n<span class=\"voicetext\">Attach documents<\/span>\n\n<div class='attachment'>\n\n<div class=\"downloaded\">\n<span><\/span>\n<div class=\"deleteFile\"><\/div>\n<\/div>\n\n<div class=\"attachmentButton\" onclick=\"(function cl(e){if(e.target.nodeName == 'DIV'){e.target.parentNode.children[1].children[0].click(); }})(arguments[0]);\">\n\n<div class=\"innerText\">Upload file<\/div>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"att-files\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\".jpg,.png,.jpeg,.pdf\" aria-invalid=\"false\" type=\"file\" name=\"att-files\" \/><\/span>\n\n<div class=\"tip\" onclick=\"event.stopPropagation()\">\n<p>You can attach 1 file up to 2MB. Valid file formats: pdf, jpg, jpeg, png.<\/p>\n<\/div>\n\n<\/div>\n\n<\/div>\n\n<\/div>\n\n\n\n<\/div>\n\n<div class=\"contact-us__wrapper\"> \n<p class=\"pp\">By clicking Send, you consent to Innowise processing your personal data per our<a href=\"\/privacy-notice\/\"> Privacy Policy <\/a>to provide you with relevant information. By submitting your phone number, you agree that we may contact you via voice calls, SMS, and messaging apps. Calling, message, and data rates may apply.<\/p>\n\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"scoring_point\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmCampaign\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmContent\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmMedium\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmSource\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utmTerm\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"location\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"city\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"ip\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"Summ\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"gclid\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"rating\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"urlCompany\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"urlWithParams\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"audioMessageLink\" \/>\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner contact-us__send\" id=\"contact-send-button\" type=\"submit\" value=\"Send\" \/>\n<\/div>\n\n<div class='mailToContact'>You can also send us your request <\/br>to <a href=\"mailto:contact@innowise.com\">contact@innowise.com<\/a><\/div>\n\n<\/div>\n\n<div class=\"elementor-widget-container\" style=\"z-index:1;\">\n<div class=\"contact__info\">\n  <div class=\"contact__info-background\"><\/div>\n  <div class=\"contact__info-heading\">What happens next?<\/div>\n  <div class=\"contact__info-steps\">\n\n    <div class=\"contact__info-block\">\n      <div class=\"contact__info-step\">1<\/div>\n      <p class=\"contact__info-text\">Once we\u2019ve received and processed your request, we\u2019ll get back to you to detail your\n        project needs and sign an NDA to ensure confidentiality.<\/p>\n    <\/div>\n\n    <div class=\"contact__info-block\">\n      <div class=\"contact__info-step\">2<\/div>\n      <p class=\"contact__info-text\">After examining your wants, needs, and expectations, our team will devise a project\n        proposal with the scope of work, team size, time, and cost estimates.<\/p>\n    <\/div>\n\n    <div class=\"contact__info-block\">\n      <div class=\"contact__info-step\">3<\/div>\n      <p class=\"contact__info-text\">We\u2019ll arrange a meeting with you to discuss the offer and nail down the details.<\/p>\n    <\/div>\n\n    <div class=\"contact__info-block\">\n      <div class=\"contact__info-step\">4<\/div>\n      <p class=\"contact__info-text\">Finally, we\u2019ll sign a contract and start working on your project right away.<\/p>\n    <\/div>\n  <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\n<\/div>\n\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"other_services_container\">[need_other_services_v2]<\/div><script>\n            jQuery( document ).ready(function($) {\n                $('[data-elementor-type=\"wp-page\"]').children().last().before($('.other_services_container'));\n                var sections = $('[data-elementor-type=\"wp-page\"]').find('.net-15.dt-16');\n                $($('#form-templates').parents('.elementor-section')).before($('.other_services_container'));\n                for(var i = 0; i<sections.length; i++){\n                    if($(sections[i]).hasClass( 'net-15' ) && $(sections[i]).hasClass( 'dt-16' ) && $(sections[i]).hasClass( 'elementor-hidden-desktop' )==false){\n                        $(sections[i]).before($('.other_services_container'));\n                        if($(sections[i]).css('background-color')=='rgb(255, 255, 255)' || $(sections[i]).css('background-color')=='rgba(0, 0, 0, 0)'){\n                            $('.other_services_container').find('.elementor-section').css('background-color','#FBFBFD');\n                        }      \n                    }\n                }\n                \n            });\n        <\/script>","protected":false},"excerpt":{"rendered":"<p>Fitness app development company With 18 years in IT, Innowise turns health and fitness app ideas into scalable products loved by users worldwide. Designed for both iOS and Android, our custom apps support training, wellness, and sports performance tracking at scale. Hire our developers 60+ health and fitness apps delivered 40+ health and fitness app [&hellip;]<\/p>\n","protected":false},"author":65,"featured_media":188933,"parent":177630,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":true,"inline_featured_image":false,"footnotes":""},"class_list":["post-137927","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/pages\/137927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/comments?post=137927"}],"version-history":[{"count":0,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/pages\/137927\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/pages\/177630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/media\/188933"}],"wp:attachment":[{"href":"https:\/\/innowise.com\/sv\/wp-json\/wp\/v2\/media?parent=137927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}